{"id":15098,"date":"2022-04-28T07:44:11","date_gmt":"2022-04-28T06:44:11","guid":{"rendered":"https:\/\/portale.unime.it\/comunicatistampa\/?p=15098"},"modified":"2022-04-28T07:44:11","modified_gmt":"2022-04-28T06:44:11","slug":"the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute","status":"publish","type":"post","link":"https:\/\/portale2.unime.it\/comunicatistampa\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\/","title":{"rendered":"\u201cTHE Impact Rankings 2022\u201d, Unime si classifica nella fascia 101-200 per l\u2019SDg3 dedicato alla Salute"},"content":{"rendered":"<div class=\"x_elementToProof\">\n<p style=\"text-align: justify\">Unime si posiziona nella fascia 101-200 su 1161 istituzioni valutate per l\u2019SDg3 \u201cHealth\u201d del THE Impact ranking 2022, una classifica specificatamente stilata per misurare l\u2019impatto delle universit\u00e0 di tutto il mondo nel loro impegno alla realizzazione degli SDG (Sustainable Development Goals), gli obiettivi per lo Sviluppo Sostenibile definiti nell\u2019Agenda 2030 delle Nazioni Unite. Rispetto allo scorso anno, Unime vanta un miglioramento nelle 2 metriche relative a \u201cRicerca\u201d e \u201cLaureati\u201d.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<p style=\"text-align: justify\">\u201cConsolidare il risultato nella \u00a0classifica THE Impact- ha detto il rettore, prof. Salvatore Cuzzocrea- \u00a0premia lo sforzo che il nostro Ateneo sta facendo per contribuire concretamente allo sviluppo sostenibile ed alla promozione degli obiettivi dell\u2019Agenda 2030. Al ranking partecipano tutte le pi\u00f9 importanti universit\u00e0 al mondo, quindi questo risultato nell\u2019obiettivo dedicato alla salute, \u00a0onora le strutture sanitarie dell\u2019Ateneo che da sempre sono al centro della ricerca e della didattica d\u2019eccellenza internazionale\u201d.<\/p>\n<div id=\"x_Signature\">\n<div>\n<div><\/div>\n<div class=\"x_elementToProof\">\n<div>\n<div>\u200b<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Unime si posiziona nella fascia 101-200 su 1161 istituzioni valutate per l\u2019SDg3 \u201cHealth\u201d del THE Impact ranking 2022, una classifica specificatamente stilata per misurare l\u2019impatto delle universit\u00e0 di tutto il mondo nel loro impegno alla realizzazione degli SDG (Sustainable Development Goals), gli obiettivi per lo Sviluppo Sostenibile definiti nell\u2019Agenda 2030 delle Nazioni Unite. Rispetto allo&hellip; <a class=\"more-link\" href=\"https:\/\/portale2.unime.it\/comunicatistampa\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\/\">Continua a leggere <span class=\"screen-reader-text\">\u201cTHE Impact Rankings 2022\u201d, Unime si classifica nella fascia 101-200 per l\u2019SDg3 dedicato alla Salute<\/span><\/a><\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-15098","post","type-post","status-publish","format-standard","hentry","category-comunicati","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cTHE Impact Rankings 2022\u201d, Unime si classifica nella fascia 101-200 per l\u2019SDg3 dedicato alla Salute - Comunicati Stampa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicatistampa.unime.it\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cTHE Impact Rankings 2022\u201d, Unime si classifica nella fascia 101-200 per l\u2019SDg3 dedicato alla Salute - Comunicati Stampa\" \/>\n<meta property=\"og:description\" content=\"Unime si posiziona nella fascia 101-200 su 1161 istituzioni valutate per l\u2019SDg3 \u201cHealth\u201d del THE Impact ranking 2022, una classifica specificatamente stilata per misurare l\u2019impatto delle universit\u00e0 di tutto il mondo nel loro impegno alla realizzazione degli SDG (Sustainable Development Goals), gli obiettivi per lo Sviluppo Sostenibile definiti nell\u2019Agenda 2030 delle Nazioni Unite. Rispetto allo&hellip; Continua a leggere \u201cTHE Impact Rankings 2022\u201d, Unime si classifica nella fascia 101-200 per l\u2019SDg3 dedicato alla Salute\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicatistampa.unime.it\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\/\" \/>\n<meta property=\"og:site_name\" content=\"Comunicati Stampa\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-28T06:44:11+00:00\" \/>\n<meta name=\"author\" content=\"astramandino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"astramandino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicatistampa.unime.it\\\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicatistampa.unime.it\\\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\\\/\"},\"author\":{\"name\":\"astramandino\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/ece3ce92132d3b80b89603a7e93eda7f\"},\"headline\":\"\u201cTHE Impact Rankings 2022\u201d, Unime si classifica nella fascia 101-200 per l\u2019SDg3 dedicato alla Salute\",\"datePublished\":\"2022-04-28T06:44:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicatistampa.unime.it\\\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\\\/\"},\"wordCount\":157,\"publisher\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#organization\"},\"articleSection\":[\"Comunicati Stampa Universit\u00e0 di Messina\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicatistampa.unime.it\\\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\\\/\",\"url\":\"https:\\\/\\\/comunicatistampa.unime.it\\\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\\\/\",\"name\":\"\u201cTHE Impact Rankings 2022\u201d, Unime si classifica nella fascia 101-200 per l\u2019SDg3 dedicato alla Salute - Comunicati Stampa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2022-04-28T06:44:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicatistampa.unime.it\\\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicatistampa.unime.it\\\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicatistampa.unime.it\\\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cTHE Impact Rankings 2022\u201d, Unime si classifica nella fascia 101-200 per l\u2019SDg3 dedicato alla Salute\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/\",\"name\":\"Comunicati Stampa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#organization\"},\"alternateName\":\"https:\\\/\\\/comunicatistampa.unime.it\\\/\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#organization\",\"name\":\"Comunicati Stampa\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/wp-content\\\/uploads\\\/sites\\\/51\\\/2024\\\/07\\\/COMUNICATI-STAMPA-2.png\",\"contentUrl\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/wp-content\\\/uploads\\\/sites\\\/51\\\/2024\\\/07\\\/COMUNICATI-STAMPA-2.png\",\"width\":1000,\"height\":346,\"caption\":\"Comunicati Stampa\"},\"image\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/ece3ce92132d3b80b89603a7e93eda7f\",\"name\":\"astramandino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g\",\"caption\":\"astramandino\"},\"url\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/author\\\/astramandino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cTHE Impact Rankings 2022\u201d, Unime si classifica nella fascia 101-200 per l\u2019SDg3 dedicato alla Salute - Comunicati Stampa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicatistampa.unime.it\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cTHE Impact Rankings 2022\u201d, Unime si classifica nella fascia 101-200 per l\u2019SDg3 dedicato alla Salute - Comunicati Stampa","og_description":"Unime si posiziona nella fascia 101-200 su 1161 istituzioni valutate per l\u2019SDg3 \u201cHealth\u201d del THE Impact ranking 2022, una classifica specificatamente stilata per misurare l\u2019impatto delle universit\u00e0 di tutto il mondo nel loro impegno alla realizzazione degli SDG (Sustainable Development Goals), gli obiettivi per lo Sviluppo Sostenibile definiti nell\u2019Agenda 2030 delle Nazioni Unite. Rispetto allo&hellip; Continua a leggere \u201cTHE Impact Rankings 2022\u201d, Unime si classifica nella fascia 101-200 per l\u2019SDg3 dedicato alla Salute","og_url":"https:\/\/comunicatistampa.unime.it\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\/","og_site_name":"Comunicati Stampa","article_published_time":"2022-04-28T06:44:11+00:00","author":"astramandino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"astramandino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicatistampa.unime.it\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\/#article","isPartOf":{"@id":"https:\/\/comunicatistampa.unime.it\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\/"},"author":{"name":"astramandino","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#\/schema\/person\/ece3ce92132d3b80b89603a7e93eda7f"},"headline":"\u201cTHE Impact Rankings 2022\u201d, Unime si classifica nella fascia 101-200 per l\u2019SDg3 dedicato alla Salute","datePublished":"2022-04-28T06:44:11+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicatistampa.unime.it\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\/"},"wordCount":157,"publisher":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#organization"},"articleSection":["Comunicati Stampa Universit\u00e0 di Messina"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicatistampa.unime.it\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\/","url":"https:\/\/comunicatistampa.unime.it\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\/","name":"\u201cTHE Impact Rankings 2022\u201d, Unime si classifica nella fascia 101-200 per l\u2019SDg3 dedicato alla Salute - Comunicati Stampa","isPartOf":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#website"},"datePublished":"2022-04-28T06:44:11+00:00","breadcrumb":{"@id":"https:\/\/comunicatistampa.unime.it\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicatistampa.unime.it\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicatistampa.unime.it\/the-impact-rankings-2022-unime-si-classifica-nella-fascia-101-200-per-lsdg3-dedicato-alla-salute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/portale2.unime.it\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"\u201cTHE Impact Rankings 2022\u201d, Unime si classifica nella fascia 101-200 per l\u2019SDg3 dedicato alla Salute"}]},{"@type":"WebSite","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#website","url":"https:\/\/portale2.unime.it\/comunicatistampa\/","name":"Comunicati Stampa","description":"","publisher":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#organization"},"alternateName":"https:\/\/comunicatistampa.unime.it\/","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portale2.unime.it\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#organization","name":"Comunicati Stampa","url":"https:\/\/portale2.unime.it\/comunicatistampa\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#\/schema\/logo\/image\/","url":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-content\/uploads\/sites\/51\/2024\/07\/COMUNICATI-STAMPA-2.png","contentUrl":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-content\/uploads\/sites\/51\/2024\/07\/COMUNICATI-STAMPA-2.png","width":1000,"height":346,"caption":"Comunicati Stampa"},"image":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#\/schema\/person\/ece3ce92132d3b80b89603a7e93eda7f","name":"astramandino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g","caption":"astramandino"},"url":"https:\/\/portale2.unime.it\/comunicatistampa\/author\/astramandino\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/posts\/15098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=15098"}],"version-history":[{"count":0,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/posts\/15098\/revisions"}],"wp:attachment":[{"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=15098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=15098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=15098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}