{"id":21197,"date":"2026-02-10T12:10:03","date_gmt":"2026-02-10T11:10:03","guid":{"rendered":"https:\/\/portale2.unime.it\/comunicatistampa\/?p=21197"},"modified":"2026-02-10T13:06:52","modified_gmt":"2026-02-10T12:06:52","slug":"presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere","status":"publish","type":"post","link":"https:\/\/portale2.unime.it\/comunicatistampa\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\/","title":{"rendered":"Presentato il Progetto &#8220;Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere&#8221;"},"content":{"rendered":"<div style=\"text-align: justify\">L&#8217;Aula Magna del Rettorato ha ospitato l&#8217;evento di presentazione del Progetto &#8220;Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere&#8221;. All&#8217;iniziativa hanno preso parte gli Istituti scolastici, le autorit\u00e0 accademiche e istituzionali.<br \/>\nDopo i saluti della\u00a0prof.ssa Candida Milone, Prorettrice alla Didattica (in collegamento da remoto), della prof.ssa Paola Dugo, Prorettrice alla Ricerca, e della prof.ssa Marina Trimarchi, Prorettrice alla Terza Missione, sono intervenuti anche la prof.ssa Cinzia Ingratoci Scorciapino, Delegata della Rettrice alla Promozione e allo sviluppo dell\u2019offerta formativa sul territorio, il prof. Dario De Salvo, docente di Storia della pedagogia e dell\u2019educazione, il prof. Leon Zingales, Provveditore agli Studi di Messina, e la prof.ssa Giuseppina D\u2019Agu\u00ec, Coordinatrice del progetto. L&#8217;incontro \u00e8 stato moderato dalla prof.ssa Consuelo Celesti.<\/div>\n<p style=\"text-align: justify\"><!--more--><\/p>\n<div style=\"text-align: justify\">L&#8217;Universit\u00e0 peloritana figura fra gli Atenei italiani finanziati dal Dipartimento per le Pari Opportunit\u00e0 della Presidenza del Consiglio dei Ministri\u00a0nell\u2019ambito dell\u2019Avviso pubblico \u201cSTEM Universit\u00e0 2024\u201d, finalizzato alla promozione di progetti innovativi per la formazione dei docenti delle scuole secondarie di primo e secondo grado nella didattica delle discipline scientifiche, tecnologiche, ingegneristiche e matematiche (STEM), con particolare attenzione allo sviluppo delle competenze STEM nelle studentesse e negli studenti. Il Progetto ha ottenuto un finanziamento di 200.000 euro\u00a0e si propone di rafforzare l\u2019innovazione didattica, l\u2019inclusione e la parit\u00e0 di genere attraverso percorsi formativi co-progettati tra Universit\u00e0 e Scuole.<\/div>\n<div style=\"text-align: justify\">&#8220;L&#8217;evento odierno &#8211; ha esordito la prof.ssa Milone &#8211; \u00e8 importante per ribadire come l&#8217;Universit\u00e0 sia focalizzata sull&#8217;importanza delle discipline STEM, che assumono un ruolo sempre pi\u00f9 importante in ragione del contributo fornito dalla scienza e dalla tecnologia al modus vivendi di ciascuno di noi. Il nuovo Progetto di UniMe \u00e8 fondamentale per far comprendere come la scienza sia alla portata di tutti; oltretutto la storia ci insegna che le donne fanno scienza a, talvolta, la guidano. Penso a\u00a0Rita Levi-Montalcini,\u00a0Marie Curie o Frances Arnold, ma anche a coloro che non hanno ricevuto il giusto riconoscimento, ad esempio,\u00a0Mileva Mari\u0107, Fisica e prima moglie di Albert Einstein. Introdurre le attivit\u00e0 STEM nelle Scuole, perci\u00f2, potr\u00e0 aiutare a cambiare percezioni e punti di vista per emergere le attitudini di ragazzi e ragazze&#8221;.<\/div>\n<div style=\"text-align: justify\">&#8220;UniMe &#8211; ha aggiunto la prof.ssa Dugo &#8211; \u00e8 un Ateneo generalista con pi\u00f9 di 100 Corsi di Laurea e numerosi percorsi post-Laurea che consentono l&#8217;accesso al mondo della ricerca. I numeri indicano, inoltre, che le donne impegnate nella scienza sono in aumento, malgrado ci sia ancora della strada da fare. Spesso il mondo femminile che opera nel panorama STEM fatica quando si trova vicino ai ruoli apicali, sia per motivazioni sociali che per compromessi di vita; anche in quest&#8217;ottica si inserisce il Progetto che presentiamo oggi, teso a divulgare le discipline STEM nelle Scuole e tra le donne. Lavoreremo, di concerto con gli Istituti scolastici, per garantire una formazione completa ai nostri giovani, innestando quei semi che potranno favorire l&#8217;apertura mentale necessaria per il loro futuro&#8221;.<\/div>\n<div style=\"text-align: justify\">&#8220;Desidero ringraziare innanzitutto la Coordinatrice del Progetto, prof.ssa Giuseppina D&#8217;Agu\u00ec, e tutti i suoi collaboratori &#8211; ha commentato la prof.ssa Trimarchi &#8211; senza i quali oggi non saremmo in quest&#8217;Aula di fronte agli alunni delle Scuole. Dobbiamo far passare il messaggio che le discipline STEM siano divertenti. Ne era convinto il Fisico Antonino Zichichi, mancato proprio ieri, che ha ideato un importante Progetto di cui anche io faccio parte. Si chiama &#8216;EEE (Extreme Energy Events)&#8217; ed ha lo scopo di scopo di studiare i raggi cosmici primari di energie estremamente alte che arrivano sulla Terra attraverso la rivelazione simultanea di muoni sui rivelatori attivi. Allo studio partecipano diversi enti di altissimo livello e, soprattutto, diversi Istituti scolastici distribuiti sul territorio nazionale che sono stati dotati di diversi telescopi di rilevazione i cui dati vengono registrati e raccolti dagli stessi studenti che, in questo modo, si comportano come veri e propri ricercatori. Grazie a questa intuizione l&#8217;Italia non solo si \u00e8 dotata, riunendo i rilevamenti, del pi\u00f9 vasto telescopio di raggi cosmici in Europa, ma ha anche fornito indicazioni utili ai professionisti di settore ed ha favorito la divulgazione scientifica tra gli alunni e le alunne del Paese. A suo modo, il progetto UniMe risponde a questa logica, con l&#8217;obiettivo di far comprendere che tutti e tutte possono abbracciare l&#8217;affascinante mondo della scienza&#8221;.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Aula Magna del Rettorato ha ospitato l&#8217;evento di presentazione del Progetto &#8220;Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere&#8221;. All&#8217;iniziativa hanno preso parte gli Istituti scolastici, le autorit\u00e0 accademiche e istituzionali. Dopo i saluti della\u00a0prof.ssa Candida Milone, Prorettrice alla Didattica (in collegamento da remoto), della prof.ssa Paola Dugo,&hellip; <a class=\"more-link\" href=\"https:\/\/portale2.unime.it\/comunicatistampa\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\/\">Continua a leggere <span class=\"screen-reader-text\">Presentato il Progetto &#8220;Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere&#8221;<\/span><\/a><\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[3248,3680,4502,4244],"class_list":["post-21197","post","type-post","status-publish","format-standard","hentry","category-comunicati","tag-progetto","tag-scuola","tag-stem","tag-unime","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentato il Progetto &quot;Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere&quot; - Comunicati Stampa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portale2.unime.it\/comunicatistampa\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentato il Progetto &quot;Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere&quot; - Comunicati Stampa\" \/>\n<meta property=\"og:description\" content=\"L&#8217;Aula Magna del Rettorato ha ospitato l&#8217;evento di presentazione del Progetto &#8220;Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere&#8221;. All&#8217;iniziativa hanno preso parte gli Istituti scolastici, le autorit\u00e0 accademiche e istituzionali. Dopo i saluti della\u00a0prof.ssa Candida Milone, Prorettrice alla Didattica (in collegamento da remoto), della prof.ssa Paola Dugo,&hellip; Continua a leggere Presentato il Progetto &#8220;Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere&#8221;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portale2.unime.it\/comunicatistampa\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\/\" \/>\n<meta property=\"og:site_name\" content=\"Comunicati Stampa\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T11:10:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T12:06:52+00:00\" \/>\n<meta name=\"author\" content=\"astramandino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"astramandino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\\\/\"},\"author\":{\"name\":\"astramandino\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/ece3ce92132d3b80b89603a7e93eda7f\"},\"headline\":\"Presentato il Progetto &#8220;Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere&#8221;\",\"datePublished\":\"2026-02-10T11:10:03+00:00\",\"dateModified\":\"2026-02-10T12:06:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\\\/\"},\"wordCount\":747,\"publisher\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#organization\"},\"keywords\":[\"progetto\",\"Scuola\",\"STEM\",\"Unime\"],\"articleSection\":[\"Comunicati Stampa Universit\u00e0 di Messina\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\\\/\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\\\/\",\"name\":\"Presentato il Progetto \\\"Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere\\\" - Comunicati Stampa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2026-02-10T11:10:03+00:00\",\"dateModified\":\"2026-02-10T12:06:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentato il Progetto &#8220;Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/\",\"name\":\"Comunicati Stampa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#organization\"},\"alternateName\":\"https:\\\/\\\/comunicatistampa.unime.it\\\/\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#organization\",\"name\":\"Comunicati Stampa\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/wp-content\\\/uploads\\\/sites\\\/51\\\/2024\\\/07\\\/COMUNICATI-STAMPA-2.png\",\"contentUrl\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/wp-content\\\/uploads\\\/sites\\\/51\\\/2024\\\/07\\\/COMUNICATI-STAMPA-2.png\",\"width\":1000,\"height\":346,\"caption\":\"Comunicati Stampa\"},\"image\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/ece3ce92132d3b80b89603a7e93eda7f\",\"name\":\"astramandino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g\",\"caption\":\"astramandino\"},\"url\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/author\\\/astramandino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentato il Progetto \"Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere\" - Comunicati Stampa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portale2.unime.it\/comunicatistampa\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\/","og_locale":"it_IT","og_type":"article","og_title":"Presentato il Progetto \"Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere\" - Comunicati Stampa","og_description":"L&#8217;Aula Magna del Rettorato ha ospitato l&#8217;evento di presentazione del Progetto &#8220;Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere&#8221;. All&#8217;iniziativa hanno preso parte gli Istituti scolastici, le autorit\u00e0 accademiche e istituzionali. Dopo i saluti della\u00a0prof.ssa Candida Milone, Prorettrice alla Didattica (in collegamento da remoto), della prof.ssa Paola Dugo,&hellip; Continua a leggere Presentato il Progetto &#8220;Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere&#8221;","og_url":"https:\/\/portale2.unime.it\/comunicatistampa\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\/","og_site_name":"Comunicati Stampa","article_published_time":"2026-02-10T11:10:03+00:00","article_modified_time":"2026-02-10T12:06:52+00:00","author":"astramandino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"astramandino","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\/#article","isPartOf":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\/"},"author":{"name":"astramandino","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#\/schema\/person\/ece3ce92132d3b80b89603a7e93eda7f"},"headline":"Presentato il Progetto &#8220;Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere&#8221;","datePublished":"2026-02-10T11:10:03+00:00","dateModified":"2026-02-10T12:06:52+00:00","mainEntityOfPage":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\/"},"wordCount":747,"publisher":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#organization"},"keywords":["progetto","Scuola","STEM","Unime"],"articleSection":["Comunicati Stampa Universit\u00e0 di Messina"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\/","url":"https:\/\/portale2.unime.it\/comunicatistampa\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\/","name":"Presentato il Progetto \"Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere\" - Comunicati Stampa","isPartOf":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#website"},"datePublished":"2026-02-10T11:10:03+00:00","dateModified":"2026-02-10T12:06:52+00:00","breadcrumb":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portale2.unime.it\/comunicatistampa\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/presentato-il-progetto-dalla-ricerca-alla-didattica-una-nuova-prospettiva-per-le-stem-e-la-parita-di-genere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/portale2.unime.it\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"Presentato il Progetto &#8220;Dalla Ricerca alla Didattica: una nuova prospettiva per le STEM e la parit\u00e0 di genere&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#website","url":"https:\/\/portale2.unime.it\/comunicatistampa\/","name":"Comunicati Stampa","description":"","publisher":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#organization"},"alternateName":"https:\/\/comunicatistampa.unime.it\/","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portale2.unime.it\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#organization","name":"Comunicati Stampa","url":"https:\/\/portale2.unime.it\/comunicatistampa\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#\/schema\/logo\/image\/","url":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-content\/uploads\/sites\/51\/2024\/07\/COMUNICATI-STAMPA-2.png","contentUrl":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-content\/uploads\/sites\/51\/2024\/07\/COMUNICATI-STAMPA-2.png","width":1000,"height":346,"caption":"Comunicati Stampa"},"image":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#\/schema\/person\/ece3ce92132d3b80b89603a7e93eda7f","name":"astramandino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g","caption":"astramandino"},"url":"https:\/\/portale2.unime.it\/comunicatistampa\/author\/astramandino\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/posts\/21197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=21197"}],"version-history":[{"count":2,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/posts\/21197\/revisions"}],"predecessor-version":[{"id":21199,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/posts\/21197\/revisions\/21199"}],"wp:attachment":[{"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=21197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=21197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=21197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}