{"id":21314,"date":"2026-05-13T13:36:17","date_gmt":"2026-05-13T11:36:17","guid":{"rendered":"https:\/\/portale2.unime.it\/comunicatistampa\/?p=21314"},"modified":"2026-05-13T14:09:27","modified_gmt":"2026-05-13T12:09:27","slug":"feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro","status":"publish","type":"post","link":"https:\/\/portale2.unime.it\/comunicatistampa\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\/","title":{"rendered":"FeedME sar\u00e0 la nuova infrastruttura di UniMe, il progetto \u00e8 stato finanziato dalla Regione per oltre 16 milioni di euro"},"content":{"rendered":"<div class=\"x_elementToProof\" style=\"text-align: justify\"><\/div>\n<div class=\"x_elementToProof\" style=\"text-align: justify\">L\u2019infrastruttura denominata Center for Food and Environmental Empowerment for the Development of the MEditerranean area\u00a0(FeedME),\u00a0che sar\u00e0 realizzata dall&#8217;Universit\u00e0 di Messina, sar\u00e0 finanziata &#8211; per un totale di 16.665.127 \u20ac &#8211; dalla Regione Siciliana nell&#8217;ambito di un programma di implementazione di un ecosistema innovativo e competitivo con le grandi reti nazionali ed europee.<\/div>\n<p style=\"text-align: justify\"><!--more--><\/p>\n<div style=\"text-align: justify\"><\/div>\n<div style=\"text-align: justify\">FeedMe si configura come una nuova Infrastruttura di Ricerca situata in un unico sito e dedicata al sostegno del settore agroalimentare; l&#8217;Ateneo messinese vanta gi\u00e0 numerose linee di ricerca fortemente strutturate nell\u2019ambito dell\u2019agro-industria e del riutilizzo degli scarti agroalimentari per finalita\u0300 di tipo farmaceutico, nutraceutico e cosmeceutico con una particolare attenzione ai concetti di sostenibilita\u0300 ed economia circolare. L\u2019infrastruttura intende favorire la creazione di sinergie tra Enti di ricerca, Universita\u0300, Aziende e Istituzioni, con l\u2019obiettivo di sviluppare metodologie e tecnologie avanzate per l\u2019intera filiera agroalimentare. Le attivita\u0300 di ricerca saranno orientate alla generazione di nuove conoscenze e alla loro applicazione concreta, con particolare attenzione all\u2019ottimizzazione dei processi produttivi, alla riduzione dell\u2019impatto ambientale e all\u2019incremento della competitivita\u0300 del settore sia a livello regionale che nazionale.<\/div>\n<div style=\"text-align: justify\"><\/div>\n<div class=\"x_elementToProof\" style=\"text-align: justify\">FeedME vedra\u0300 il coinvolgimento attivo di diversi Dipartimenti universitari, a testimonianza della natura interdisciplinare del progetto. Saranno coinvolti il Dipartimento di Scienze Chimiche, Biologiche, Farmaceutiche e Ambientali\u00a0(per l\u2019analisi e la valorizzazione delle sostanze chimiche di interesse presenti nei sottoprodotti agroalimentari e marini), il Dipartimento di Scienze Veterinarie\u00a0(per lo studio della sicurezza alimentare, della qualita\u0300 nutrizionale e della salute animale nel contesto agroalimentare), il Dipartimento di Scienze Biomediche, Odontoiatriche e delle Immagini Morfologiche e Funzionali\u00a0(per la ricerca sugli effetti salutistici dei prodotti agroalimentari e lo sviluppo di nuove applicazioni in campo biomedicale), il Dipartimento di Economia\u00a0(per l\u2019analisi dell\u2019impatto economico delle innovazioni sviluppate, la sostenibilita\u0300 dei modelli di economia circolare e la competitivita\u0300 del settore agroalimentare) ed il Dipartimento di Ingegneria\u00a0(per lo sviluppo e l\u2019implementazione di tecnologie avanzate, sistemi di automazione e soluzioni innovative per la produzione agroalimentare sostenibile).<\/div>\n<div style=\"text-align: justify\"><\/div>\n<div style=\"text-align: justify\">L&#8217;organizzazione di FeedME e\u0300 articolata su piu\u0300 livelli, con ruoli complementari e ben definiti tra direzione strategica, gestione operativa, supervisione scientifica e sostenibilita\u0300 economica. Il Coordinatore Scientifico sar\u00e0 la\u00a0prof.ssa Nunziacarla Span\u00f2, il Responsabile Amministrativo sar\u00e0 il\u00a0dott. Pierfrancesco Donato. Il nucleo strategico incaricato della programmazione e del monitoraggio delle attivit\u00e0 progettuali sar\u00e0 composto dai proff. Alessandra Bitto, Paola Dugo, Antonino German\u00e0, e Michele Limosani. \u00a0Ulteriori livelli includeranno la Cabina di Pilotaggio ed il Comitato Tecnico\/Scientifico, supportati da un Comitato Comunicazione e Networking.<\/div>\n<div style=\"text-align: justify\"><\/div>\n<div class=\"x_elementToProof\" style=\"text-align: justify\">&#8220;La Regione Siciliana &#8211; commenta la Prorettrice alla Ricerca, prof.ssa Paola Dugo &#8211; ha deciso di finanziare per un totale di oltre 16 milioni di euro il progetto FeedME del nostro Ateneo, certificandone la validit\u00e0 scientifica e riconoscendone l\u2019impatto territoriale. Per le attivit\u00e0 progettuali di ricerca, FeedME convoglier\u00e0 in un unico punto di competenze accademiche e tecnologiche integrate e consentir\u00e0 di affrontare le sfide della filiera agroalimentare in modo sinergico e integrato, promuovendo l\u2019innovazione e la sostenibilit\u00e0 attraverso un approccio scientificamente fondato e interdisciplinare. La sede progettuale, difatti, sar\u00e0 ospitata presso l\u2019ex Facolta\u0300 di Farmacia, con spazi attrezzati e adeguati alle esigenze di ricerca. FeedME si inserira\u0300 in un contesto accademico e scientifico gia\u0300 molto attivo e prolifico, vicino al laboratorio MeIT, coordinato dal prof. Luigi Mondello, con specifiche competenze nel settore analitico-alimentare. In tal modo il progetto, nell&#8217;arco del prossimo biennio, si propone di divenire un punto di riferimento concreto per lo sviluppo di nuove soluzioni nel settore Food &amp; Feed, con un impatto positivo non solo sulla ricerca, ma anche sull\u2019economia del territorio e dell&#8217;Isola. FeedME rappresenta una scelta fortemente voluta dalla Rettrice, prof.ssa Giovanna Spatari, che ringraziamo per il fattivo supporto&#8221;.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019infrastruttura denominata Center for Food and Environmental Empowerment for the Development of the MEditerranean area\u00a0(FeedME),\u00a0che sar\u00e0 realizzata dall&#8217;Universit\u00e0 di Messina, sar\u00e0 finanziata &#8211; per un totale di 16.665.127 \u20ac &#8211; dalla Regione Siciliana nell&#8217;ambito di un programma di implementazione di un ecosistema innovativo e competitivo con le grandi reti nazionali ed europee.<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[4666,1688,4244],"class_list":["post-21314","post","type-post","status-publish","format-standard","hentry","category-senza-categoria","tag-feedme","tag-filiera-agroalimentare","tag-unime","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FeedME sar\u00e0 la nuova infrastruttura di UniMe, il progetto \u00e8 stato finanziato dalla Regione per oltre 16 milioni di euro - Comunicati Stampa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portale2.unime.it\/comunicatistampa\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FeedME sar\u00e0 la nuova infrastruttura di UniMe, il progetto \u00e8 stato finanziato dalla Regione per oltre 16 milioni di euro - Comunicati Stampa\" \/>\n<meta property=\"og:description\" content=\"L\u2019infrastruttura denominata Center for Food and Environmental Empowerment for the Development of the MEditerranean area\u00a0(FeedME),\u00a0che sar\u00e0 realizzata dall&#8217;Universit\u00e0 di Messina, sar\u00e0 finanziata &#8211; per un totale di 16.665.127 \u20ac &#8211; dalla Regione Siciliana nell&#8217;ambito di un programma di implementazione di un ecosistema innovativo e competitivo con le grandi reti nazionali ed europee.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portale2.unime.it\/comunicatistampa\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\/\" \/>\n<meta property=\"og:site_name\" content=\"Comunicati Stampa\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T11:36:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T12:09:27+00:00\" \/>\n<meta name=\"author\" content=\"astramandino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"astramandino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\\\/\"},\"author\":{\"name\":\"astramandino\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/ece3ce92132d3b80b89603a7e93eda7f\"},\"headline\":\"FeedME sar\u00e0 la nuova infrastruttura di UniMe, il progetto \u00e8 stato finanziato dalla Regione per oltre 16 milioni di euro\",\"datePublished\":\"2026-05-13T11:36:17+00:00\",\"dateModified\":\"2026-05-13T12:09:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\\\/\"},\"wordCount\":639,\"publisher\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#organization\"},\"keywords\":[\"FeedME\",\"filiera agroalimentare\",\"Unime\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\\\/\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\\\/\",\"name\":\"FeedME sar\u00e0 la nuova infrastruttura di UniMe, il progetto \u00e8 stato finanziato dalla Regione per oltre 16 milioni di euro - Comunicati Stampa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2026-05-13T11:36:17+00:00\",\"dateModified\":\"2026-05-13T12:09:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FeedME sar\u00e0 la nuova infrastruttura di UniMe, il progetto \u00e8 stato finanziato dalla Regione per oltre 16 milioni di euro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/\",\"name\":\"Comunicati Stampa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#organization\"},\"alternateName\":\"https:\\\/\\\/comunicatistampa.unime.it\\\/\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#organization\",\"name\":\"Comunicati Stampa\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/wp-content\\\/uploads\\\/sites\\\/51\\\/2024\\\/07\\\/COMUNICATI-STAMPA-2.png\",\"contentUrl\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/wp-content\\\/uploads\\\/sites\\\/51\\\/2024\\\/07\\\/COMUNICATI-STAMPA-2.png\",\"width\":1000,\"height\":346,\"caption\":\"Comunicati Stampa\"},\"image\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/ece3ce92132d3b80b89603a7e93eda7f\",\"name\":\"astramandino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g\",\"caption\":\"astramandino\"},\"url\":\"https:\\\/\\\/portale2.unime.it\\\/comunicatistampa\\\/author\\\/astramandino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FeedME sar\u00e0 la nuova infrastruttura di UniMe, il progetto \u00e8 stato finanziato dalla Regione per oltre 16 milioni di euro - Comunicati Stampa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portale2.unime.it\/comunicatistampa\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\/","og_locale":"it_IT","og_type":"article","og_title":"FeedME sar\u00e0 la nuova infrastruttura di UniMe, il progetto \u00e8 stato finanziato dalla Regione per oltre 16 milioni di euro - Comunicati Stampa","og_description":"L\u2019infrastruttura denominata Center for Food and Environmental Empowerment for the Development of the MEditerranean area\u00a0(FeedME),\u00a0che sar\u00e0 realizzata dall&#8217;Universit\u00e0 di Messina, sar\u00e0 finanziata &#8211; per un totale di 16.665.127 \u20ac &#8211; dalla Regione Siciliana nell&#8217;ambito di un programma di implementazione di un ecosistema innovativo e competitivo con le grandi reti nazionali ed europee.","og_url":"https:\/\/portale2.unime.it\/comunicatistampa\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\/","og_site_name":"Comunicati Stampa","article_published_time":"2026-05-13T11:36:17+00:00","article_modified_time":"2026-05-13T12:09:27+00:00","author":"astramandino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"astramandino","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\/#article","isPartOf":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\/"},"author":{"name":"astramandino","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#\/schema\/person\/ece3ce92132d3b80b89603a7e93eda7f"},"headline":"FeedME sar\u00e0 la nuova infrastruttura di UniMe, il progetto \u00e8 stato finanziato dalla Regione per oltre 16 milioni di euro","datePublished":"2026-05-13T11:36:17+00:00","dateModified":"2026-05-13T12:09:27+00:00","mainEntityOfPage":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\/"},"wordCount":639,"publisher":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#organization"},"keywords":["FeedME","filiera agroalimentare","Unime"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\/","url":"https:\/\/portale2.unime.it\/comunicatistampa\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\/","name":"FeedME sar\u00e0 la nuova infrastruttura di UniMe, il progetto \u00e8 stato finanziato dalla Regione per oltre 16 milioni di euro - Comunicati Stampa","isPartOf":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#website"},"datePublished":"2026-05-13T11:36:17+00:00","dateModified":"2026-05-13T12:09:27+00:00","breadcrumb":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portale2.unime.it\/comunicatistampa\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/feedme-sara-la-nuova-infrastruttura-di-unime-il-progetto-e-stato-finanziato-dalla-regione-per-oltre-16-milioni-di-euro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/portale2.unime.it\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"FeedME sar\u00e0 la nuova infrastruttura di UniMe, il progetto \u00e8 stato finanziato dalla Regione per oltre 16 milioni di euro"}]},{"@type":"WebSite","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#website","url":"https:\/\/portale2.unime.it\/comunicatistampa\/","name":"Comunicati Stampa","description":"","publisher":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#organization"},"alternateName":"https:\/\/comunicatistampa.unime.it\/","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portale2.unime.it\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#organization","name":"Comunicati Stampa","url":"https:\/\/portale2.unime.it\/comunicatistampa\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#\/schema\/logo\/image\/","url":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-content\/uploads\/sites\/51\/2024\/07\/COMUNICATI-STAMPA-2.png","contentUrl":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-content\/uploads\/sites\/51\/2024\/07\/COMUNICATI-STAMPA-2.png","width":1000,"height":346,"caption":"Comunicati Stampa"},"image":{"@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/portale2.unime.it\/comunicatistampa\/#\/schema\/person\/ece3ce92132d3b80b89603a7e93eda7f","name":"astramandino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/350a04f01afddd3a9f6e057c2d618be834d7ca1192086cfd02adaba43a0e0575?s=96&d=mm&r=g","caption":"astramandino"},"url":"https:\/\/portale2.unime.it\/comunicatistampa\/author\/astramandino\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/posts\/21314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=21314"}],"version-history":[{"count":3,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/posts\/21314\/revisions"}],"predecessor-version":[{"id":21317,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/posts\/21314\/revisions\/21317"}],"wp:attachment":[{"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=21314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=21314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portale2.unime.it\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=21314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}