{"id":607,"date":"2015-03-20T12:09:03","date_gmt":"2015-03-20T11:09:03","guid":{"rendered":"http:\/\/portale.unime.it\/dico\/?p=607"},"modified":"2015-03-20T12:09:03","modified_gmt":"2015-03-20T11:09:03","slug":"che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia","status":"publish","type":"post","link":"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/","title":{"rendered":"Che cos\u2019hanno in comune i barattoli e la poesia? La magia"},"content":{"rendered":"<p>L\u2019aggettivo <em>ermetico<\/em> ha a che fare con un mistero della storia della cultura occidentale. Pochi personaggi storici sono pi\u00f9 inafferrabili di Ermete Trismegisto (\u2018tre volte grandissimo\u2019): un dio, il figlio di un dio, l\u2019aiutante di un dio, un mago, un filosofo? Oppure nessuno, un nome senza sostanza, creato per raggruppare sotto un unico autore un insieme di opere misteriose dal contenuto vagamente assimilabile.<\/p>\n<p>Il dibattito sulla storicit\u00e0 di Ermete Trismegisto, sulla sua identit\u00e0, sull\u2019epoca storica in cui visse, sulla sua provenienza risale al Quindicesimo secolo, quando un monaco fiorentino trov\u00f2 a Bisanzio e port\u00f2 in patria il <em>corpus hermeticum<\/em>, l\u2019insieme di opere misteriose di cui sopra, raccolto da un erudito bizantino, Michele Psello. A quell\u2019epoca, non solo nessuno dubit\u00f2 della storicit\u00e0 di questo mago-filosofo-semidio, ma costui fu assimilato al dio greco Hermes \u2013 Mercurio per i romani \u2013 e gli furono attribuiti meriti eccezionali, tra cui quello di aver ispirato con le sue idee, tratte dalla sapienza egizia, nientemeno che Mos\u00e8, Platone, Pitagora e altri grandi pensatori antichi. Stando a questa attribuzione, Ermete sarebbe stato il fondatore della civilt\u00e0 occidentale come la conosciamo oggi.<\/p>\n<p>A partire dal Cinquecento, diversi autori hanno cominciato a ridimensionare l\u2019eccezionalit\u00e0 di Ermete, sostenendo che non fosse cos\u00ec antico come si credeva, che non avesse niente a che fare con il dio greco, che non avesse niente a che fare neanche con gli antichi egizi, e che, tutto sommato, magari non era mai esistito.<\/p>\n<p>Non tutti, nel corso della storia moderna, hanno sposato questa visione razionalistica del problema, preferendo lasciare almeno un dubbio sulla storicit\u00e0 di Ermete. Indipendentemente dall\u2019autore e dall\u2019epoca di composizione, comunque, il <em>corpus<\/em> ha avuto una enorme fortuna tra gli alchimisti seicenteschi, perch\u00e9 descrive, tra le altre cose, alcune pratiche magiche legate agli spiriti e ai demoni, alla medicina e alla manipolazione dei minerali. Una di queste ultime \u00e8 il modo di chiudere un contenitore di vetro fondendone i bordi in modo che aderiscano perfettamente tra loro e pressando sul punto della chiusura il sigillo con il simbolo di Ermete. Si otteneva, cos\u00ec, una chiusura <em>ermetica<\/em>. Questo procedimento, che aveva una funzione essenzialmente simbolica (la chiusura \u00e8 il simbolo dell\u2019impossibilit\u00e0 di comprendere la verit\u00e0), aveva anche un risvolto pratico, tanto che col tempo (si trovano gi\u00e0 esempi all\u2019inizio dell\u2019Ottocento) l\u2019aggettivo <em>ermetico<\/em> fu usato comunemente col significato di \u2018impenetrabile\u2019, riferito a qualsiasi tipo di chiusura.<\/p>\n<p>La figura di Ermete Trismegisto ha esercitato un forte fascino anche fuori dalla cerchia degli alchimisti. A questo hanno giovato il mistero sulla sua identit\u00e0 e addirittura sulla sua storicit\u00e0; ma anche il fatto che incarni l\u2019incontro delle maggiori tradizioni culturali antiche, quella egizia, quella greca e quella ebraica; per non parlare della sua caratterizzazione come mago, cio\u00e8 come depositario di una sapienza iniziatica ed esclusiva.<\/p>\n<p>A ben vedere, per\u00f2, la qualit\u00e0 principale di Ermete \u00e8 la comunicazione: le pratiche attribuite a questo personaggio mettono in comunicazione il mondo sensibile con quello trascendentale, e le parole contenute nel <em>corpus<\/em> trasmettono la conoscenza di quella realt\u00e0 nascosta ai lettori (almeno a quelli che possono capire). In senso moderno, Ermete \u00e8 un poeta: come i poeti capisce e usa il potere della parola di descrivere (ma non di spiegare) ci\u00f2 che non pu\u00f2 essere sperimentato con i sensi. A partire dal 1936, anno di pubblicazione del saggio <em>La poesia ermetica<\/em> di Francesco Flora, il titolo di <em>ermetici<\/em> \u00e8 riservato solamente ad alcuni poeti, come Ungaretti, Quasimodo e Montale; in senso lato, per\u00f2, tutti i poeti sono ermetici, esploratori del mistero, comunicatori dell\u2019inconoscibile, maghi della parola.<\/p>\n<p>Fabio Ruggiano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019aggettivo ermetico ha a che fare con un mistero della storia della cultura occidentale. Pochi personaggi storici sono pi\u00f9 inafferrabili di Ermete Trismegisto (\u2018tre volte grandissimo\u2019): un dio, il figlio di un dio, l\u2019aiutante di un dio, un mago, un filosofo? Oppure nessuno, un nome senza sostanza, creato per raggruppare sotto un unico autore un&hellip; <a class=\"more-link\" href=\"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/\">Continua a leggere <span class=\"screen-reader-text\">Che cos\u2019hanno in comune i barattoli e la poesia? La magia<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[34,93,151,290],"class_list":["post-607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-parola-che-non-ti-aspetti","tag-bizantino","tag-etimologia","tag-latino","tag-umanesimo","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Che cos\u2019hanno in comune i barattoli e la poesia? La magia - DICO - Dubbi sull&#039;Italiano Consulenza Online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Che cos\u2019hanno in comune i barattoli e la poesia? La magia - DICO - Dubbi sull&#039;Italiano Consulenza Online\" \/>\n<meta property=\"og:description\" content=\"L\u2019aggettivo ermetico ha a che fare con un mistero della storia della cultura occidentale. Pochi personaggi storici sono pi\u00f9 inafferrabili di Ermete Trismegisto (\u2018tre volte grandissimo\u2019): un dio, il figlio di un dio, l\u2019aiutante di un dio, un mago, un filosofo? Oppure nessuno, un nome senza sostanza, creato per raggruppare sotto un unico autore un&hellip; Continua a leggere Che cos\u2019hanno in comune i barattoli e la poesia? La magia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/\" \/>\n<meta property=\"og:site_name\" content=\"DICO - Dubbi sull&#039;Italiano Consulenza Online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100057634840155\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-20T11:09:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portale2.unime.it\/dico\/wp-content\/uploads\/sites\/6\/2017\/06\/20150320115606campbell.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"223\" \/>\n\t<meta property=\"og:image:height\" content=\"399\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dico_unime\" \/>\n<meta name=\"twitter:site\" content=\"@dico_unime\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/2015\\\/03\\\/20\\\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/2015\\\/03\\\/20\\\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Che cos\u2019hanno in comune i barattoli e la poesia? La magia\",\"datePublished\":\"2015-03-20T11:09:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/2015\\\/03\\\/20\\\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\\\/\"},\"wordCount\":604,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dico.unime.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/2015\\\/03\\\/20\\\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/06\\\/20150320115606campbell.jpg\",\"keywords\":[\"bizantino\",\"etimologia\",\"latino\",\"umanesimo\"],\"articleSection\":[\"La parola che non ti aspetti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/2015\\\/03\\\/20\\\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/2015\\\/03\\\/20\\\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\\\/\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/2015\\\/03\\\/20\\\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\\\/\",\"name\":\"Che cos\u2019hanno in comune i barattoli e la poesia? La magia - DICO - Dubbi sull&#039;Italiano Consulenza Online\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dico.unime.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/2015\\\/03\\\/20\\\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/2015\\\/03\\\/20\\\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/06\\\/20150320115606campbell.jpg\",\"datePublished\":\"2015-03-20T11:09:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/2015\\\/03\\\/20\\\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/2015\\\/03\\\/20\\\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/2015\\\/03\\\/20\\\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/06\\\/20150320115606campbell.jpg\",\"contentUrl\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/06\\\/20150320115606campbell.jpg\",\"width\":223,\"height\":399,\"caption\":\"ipp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/2015\\\/03\\\/20\\\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Che cos\u2019hanno in comune i barattoli e la poesia? La magia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dico.unime.it\\\/#website\",\"url\":\"https:\\\/\\\/dico.unime.it\\\/\",\"name\":\"DICO - Dubbi sull&#039;Italiano Consulenza Online\",\"description\":\"Dubbi sull&#039;italiano\",\"publisher\":{\"@id\":\"https:\\\/\\\/dico.unime.it\\\/#organization\"},\"alternateName\":\"DICO\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dico.unime.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dico.unime.it\\\/#organization\",\"name\":\"DICO - Dubbi sull&#039;Italiano Consulenza Online\",\"url\":\"https:\\\/\\\/dico.unime.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/dico.unime.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/01\\\/dico-unime.png\",\"contentUrl\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/01\\\/dico-unime.png\",\"width\":536,\"height\":189,\"caption\":\"DICO - Dubbi sull&#039;Italiano Consulenza Online\"},\"image\":{\"@id\":\"https:\\\/\\\/dico.unime.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100057634840155\",\"https:\\\/\\\/x.com\\\/dico_unime\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/dico\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Che cos\u2019hanno in comune i barattoli e la poesia? La magia - DICO - Dubbi sull&#039;Italiano Consulenza Online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/","og_locale":"it_IT","og_type":"article","og_title":"Che cos\u2019hanno in comune i barattoli e la poesia? La magia - DICO - Dubbi sull&#039;Italiano Consulenza Online","og_description":"L\u2019aggettivo ermetico ha a che fare con un mistero della storia della cultura occidentale. Pochi personaggi storici sono pi\u00f9 inafferrabili di Ermete Trismegisto (\u2018tre volte grandissimo\u2019): un dio, il figlio di un dio, l\u2019aiutante di un dio, un mago, un filosofo? Oppure nessuno, un nome senza sostanza, creato per raggruppare sotto un unico autore un&hellip; Continua a leggere Che cos\u2019hanno in comune i barattoli e la poesia? La magia","og_url":"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/","og_site_name":"DICO - Dubbi sull&#039;Italiano Consulenza Online","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100057634840155","article_published_time":"2015-03-20T11:09:03+00:00","og_image":[{"width":223,"height":399,"url":"https:\/\/portale2.unime.it\/dico\/wp-content\/uploads\/sites\/6\/2017\/06\/20150320115606campbell.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@dico_unime","twitter_site":"@dico_unime","twitter_misc":{"Scritto da":"","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/#article","isPartOf":{"@id":"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/"},"author":{"name":"","@id":""},"headline":"Che cos\u2019hanno in comune i barattoli e la poesia? La magia","datePublished":"2015-03-20T11:09:03+00:00","mainEntityOfPage":{"@id":"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/"},"wordCount":604,"commentCount":0,"publisher":{"@id":"https:\/\/dico.unime.it\/#organization"},"image":{"@id":"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/#primaryimage"},"thumbnailUrl":"https:\/\/portale2.unime.it\/dico\/wp-content\/uploads\/sites\/6\/2017\/06\/20150320115606campbell.jpg","keywords":["bizantino","etimologia","latino","umanesimo"],"articleSection":["La parola che non ti aspetti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/#respond"]}]},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/","url":"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/","name":"Che cos\u2019hanno in comune i barattoli e la poesia? La magia - DICO - Dubbi sull&#039;Italiano Consulenza Online","isPartOf":{"@id":"https:\/\/dico.unime.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/#primaryimage"},"image":{"@id":"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/#primaryimage"},"thumbnailUrl":"https:\/\/portale2.unime.it\/dico\/wp-content\/uploads\/sites\/6\/2017\/06\/20150320115606campbell.jpg","datePublished":"2015-03-20T11:09:03+00:00","breadcrumb":{"@id":"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/#primaryimage","url":"https:\/\/portale2.unime.it\/dico\/wp-content\/uploads\/sites\/6\/2017\/06\/20150320115606campbell.jpg","contentUrl":"https:\/\/portale2.unime.it\/dico\/wp-content\/uploads\/sites\/6\/2017\/06\/20150320115606campbell.jpg","width":223,"height":399,"caption":"ipp"},{"@type":"BreadcrumbList","@id":"https:\/\/portale2.unime.it\/dico\/2015\/03\/20\/che-coshanno-in-comune-i-barattoli-e-la-poesia-la-magia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/portale2.unime.it\/dico\/"},{"@type":"ListItem","position":2,"name":"Che cos\u2019hanno in comune i barattoli e la poesia? La magia"}]},{"@type":"WebSite","@id":"https:\/\/dico.unime.it\/#website","url":"https:\/\/dico.unime.it\/","name":"DICO - Dubbi sull&#039;Italiano Consulenza Online","description":"Dubbi sull&#039;italiano","publisher":{"@id":"https:\/\/dico.unime.it\/#organization"},"alternateName":"DICO","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dico.unime.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/dico.unime.it\/#organization","name":"DICO - Dubbi sull&#039;Italiano Consulenza Online","url":"https:\/\/dico.unime.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dico.unime.it\/#\/schema\/logo\/image\/","url":"https:\/\/portale2.unime.it\/dico\/wp-content\/uploads\/sites\/6\/2023\/01\/dico-unime.png","contentUrl":"https:\/\/portale2.unime.it\/dico\/wp-content\/uploads\/sites\/6\/2023\/01\/dico-unime.png","width":536,"height":189,"caption":"DICO - Dubbi sull&#039;Italiano Consulenza Online"},"image":{"@id":"https:\/\/dico.unime.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100057634840155","https:\/\/x.com\/dico_unime"]},{"@type":"Person","@id":"","url":"https:\/\/portale2.unime.it\/dico\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/portale2.unime.it\/dico\/wp-json\/wp\/v2\/posts\/607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portale2.unime.it\/dico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portale2.unime.it\/dico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portale2.unime.it\/dico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/portale2.unime.it\/dico\/wp-json\/wp\/v2\/comments?post=607"}],"version-history":[{"count":0,"href":"https:\/\/portale2.unime.it\/dico\/wp-json\/wp\/v2\/posts\/607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portale2.unime.it\/dico\/wp-json\/wp\/v2\/media\/608"}],"wp:attachment":[{"href":"https:\/\/portale2.unime.it\/dico\/wp-json\/wp\/v2\/media?parent=607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portale2.unime.it\/dico\/wp-json\/wp\/v2\/categories?post=607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portale2.unime.it\/dico\/wp-json\/wp\/v2\/tags?post=607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}