{"id":6,"date":"2026-06-18T10:14:10","date_gmt":"2026-06-18T08:14:10","guid":{"rendered":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/?page_id=6"},"modified":"2026-07-07T09:09:24","modified_gmt":"2026-07-07T07:09:24","slug":"home-repertorio-siti-e-risorse-per-il-russo","status":"publish","type":"page","link":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/","title":{"rendered":"Home &#8211; Repertorio Siti e Risorse per il Russo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6\" class=\"elementor elementor-6\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8680a58 e-con-full e-flex e-con e-parent\" data-id=\"8680a58\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-418a7e15 elementor-widget-mobile__width-initial elementor-widget elementor-widget-ucaddon_transparent_split_hero\" data-id=\"418a7e15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_transparent_split_hero.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- start Transparent Split Hero -->\n\t\t<link id='uc_ac_assets_file_uc_photography_header_css_0-css' href='https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/ac_assets\/uc_photography_header\/uc_photography_header.css' type='text\/css' rel='stylesheet' >\n\n\t\t\t<style type=\"text\/css\">\/* widget: Transparent Split Hero *\/\n\n.uc_photography_header *{\n\tmargin:0;\n\tpadding:0;\n\t-webkit-box-sizing: border-box;\n\t-moz-box-sizing: border-box;\n\tbox-sizing: border-box;\n\t\n}\n#uc_transparent_split_hero_elementor_418a7e15\n{\n\tposition:relative;\n\twidth:100%;\n    background-position:center;\n    background-size:cover;\n    background-image:url(https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/risorse-russo.png);\n    display:flex;\n    overflow:hidden;\n    \n}\n\n#uc_transparent_split_hero_elementor_418a7e15 > div\n{\n  height:100%;\n  display:flex;\n    align-items:center;\n}\n\n.uc_photography_header .uc_container_text_box{ \n  text-align:left;\n}\n.uc_photography_header .uc_subtitle\n{\n  font-size:42px;\n}\n\t\n.uc_photography_header .uc_container_text_box a{\n\tborder-style:solid;\n\tdisplay:inline-block;\n}\n\n<\/style>\n\n\t\t\t<div class=\"uc_photography_header\" id=\"uc_transparent_split_hero_elementor_418a7e15\">    \t      \n  <div class=\"uc_container_text_box\">  \n  <div>\n                <div class=\"uc_title\">Repertorio ragionato dei<\/div>        <div class=\"uc_subtitle\">SITI e delle RISORSE ONLINE<\/div>        <div class=\"uc_text\">per l'apprendimento e l'insegnamento del russo<\/div>            <\/div>\n  <\/div>\n<\/div>\n\t\t\t<!-- end Transparent Split Hero -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4273f7f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4273f7f4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c61ad6f\" data-id=\"c61ad6f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-b66e48e e-con e-atomic-element e-flexbox-base e-e563ca8 \" data-id=\"b66e48e\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"b66e48e\">\n    <div class=\"elementor-element elementor-element-e2efddd e-con e-atomic-element e-flexbox-base e-40b1e68 \" data-id=\"e2efddd\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"e2efddd\">\n    \t\t<div class=\"elementor-element elementor-element-ffdec0d elementor-widget elementor-widget-text-editor\" data-id=\"ffdec0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Competenza fonetica e fonologica<\/strong><\/h3><p><span style=\"font-size: 14pt;\">Tra le varie risorse disponibili in rete, per lo sviluppo della competenza fonetica e della competenza fonologica, in particolare, segnaliamo:<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fabf584 elementor-widget elementor-widget-ucaddon_content_accordion\" data-id=\"fabf584\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_content_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- start Content Accordion -->\n\t\t<link id='font-awesome-css' href='https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome5\/css\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome5\/css\/fontawesome-v4-shims.css' type='text\/css' rel='stylesheet' >\n\n\t\t\t<style type=\"text\/css\">\/* widget: Content Accordion *\/\n\n\n\n#uc_content_accordion_elementor_fabf584 *{\n  box-sizing: border-box;\n}\n\n#uc_content_accordion_elementor_fabf584 .ue_heading_title{\n  margin:0;\n  flex-grow:1;\n  display:flex;\n  flex-direction:row;\n}\n\n#uc_content_accordion_elementor_fabf584 .uc_container .uc-heading{\n\tdisplay:flex;\n    align-items:center;\n\toverflow:hidden;\n\tcursor:pointer;  \n}\n\n#uc_content_accordion_elementor_fabf584 .uc_container .uc_content{\n    display:none;\n}\n\n#uc_content_accordion_elementor_fabf584 .uc_container .uc-heading span.ue_accordion_icon{\n\tdisplay:flex;\n    align-items:center;\n   \tjustify-content:center;\n    flex-grow:0;\n    flex-shrink:0;\n}\n\n#uc_content_accordion_elementor_fabf584 .uc_ac_box.uc-item-active span.uc_dactive{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_fabf584 .uc_ac_box:not(.uc-item-active) span.uc_active{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_fabf584 span.ue_accordion_icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_content_accordion_elementor_fabf584 .uc_container .uc_btn {\n    text-align: center;\n    display: inline-block;\n    text-decoration: none;\n    transition: ease-in-out all 0.25s;\n}\n\n#uc_content_accordion_elementor_fabf584 .ue-item-image img{\n  width:100%;\n  display:block;\n  object-fit:cover;\n}\n\n<\/style>\n\n\t\t\t<div class=\"uc_material_accordion  \"  id=\"uc_content_accordion_elementor_fabf584\"  data-name=\"\" data-scroll=\"off\" data-offset=\"0\" data-closeothers=\"true\" data-set-hash=\"false\" data-transition-duration=\"400\" >\n  <div class=\"uc_container uc-items-wrapper\">\n    \n\n\n\n\n<div id=\"#ue-tab1\" class=\"uc_ac_box elementor-repeater-item-7dcfa21 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Be My Guest \u2013 Russian Online<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"121\"><p>Nome<\/p><\/td><td width=\"529\"><p><strong><em>Be My Guest \u2013 Russian Online<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"121\"><p>Indirizzo Internet<\/p><\/td><td width=\"529\"><p><u>http:\/\/elrusoenespana.com\/russianonline\/course\/index.php?categoryid=2&amp;lang=en<\/u><\/p><\/td><\/tr><tr><td width=\"121\"><p>Livello<\/p><\/td><td width=\"529\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"121\"><p>Parole chiave<\/p><\/td><td width=\"529\"><p><strong>Fonetica<\/strong>, lessico, dialoghi, test di livello, file audio per la comprensione del testo orale, turismo.<\/p><\/td><\/tr><tr><td width=\"121\"><p>Contenuti<\/p><\/td><td width=\"529\"><p>Attivit\u00e0 di ascolto e produzione scritta, esercizi interattivi, test di livello.<\/p><\/td><\/tr><tr><td width=\"121\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"529\"><p>I livelli del <em>QCER <\/em>sono esplicitati; in ogni lezione sono presenti test di livello per controllare i progressi fatti; sono proposti moltissimi file audio e dialoghi, utili per lavorare sulla fonetica e sulla comprensione orale; possibilit\u00e0 di contattare via Skype gli autori per chiedere chiarimenti su eventuali dubbi; forum di discussione.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab2\" class=\"uc_ac_box elementor-repeater-item-eccb2f9 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Retour. Russian for Tourism<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"127\"><p>Nome<\/p><\/td><td width=\"523\"><p><strong><em>Retour. <\/em><\/strong><strong><em>Russian for Tourism<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"127\"><p>Indirizzo Internet<\/p><\/td><td width=\"523\"><p><a href=\"http:\/\/www.russian-for-tourism.eu\">www.russian-for-tourism.eu<\/a><\/p><p><a href=\"https:\/\/www.ihf.ie\/sites\/default\/files\/upload\/04_retour_newsletter_en.pdf\">https:\/\/www.ihf.ie\/sites\/default\/files\/upload\/04_retour_newsletter_en.pdf<\/a><\/p><\/td><\/tr><tr><td width=\"127\"><p>Livello<\/p><\/td><td width=\"523\"><p>Da 0 a A2<\/p><\/td><\/tr><tr><td width=\"127\"><p>Parole chiave<\/p><\/td><td width=\"523\"><p><strong>Fonetica<\/strong>, morfosintassi, lessico, russo per il turismo, prospettiva interculturale.<\/p><\/td><\/tr><tr><td width=\"127\"><p>Contenuti<\/p><\/td><td width=\"523\"><p>Questa risorsa, la cui interfaccia \u00e8 disponibile anche in italiano, \u00e8 pensata per principianti assoluti; comprende 30 unit\u00e0, suddivise in 6 moduli, che propongono situazioni tipiche all\u2019interno di hotel, ristoranti, negozi ecc.; guida per l\u2019insegnante e per l\u2019apprendente, file audio accompagnati dalla trascrizione dei testi, esercizi e test.<\/p><\/td><\/tr><tr><td width=\"127\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"523\"><p>Spiegazioni chiare ed essenziali accompagnate da numerose attivit\u00e0 didattiche corredate da consegne chiare; possibilit\u00e0 per l\u2019apprendente di registrare la propria pronuncia; tutorial per l\u2019utilizzo della risorsa; oltre all\u2019italiano, il corso \u00e8 disponibile in altre lingue (inglese, francese, spagnolo, bulgaro, greco); sei video per pianificare un programma di apprendimento personalizzato.<\/p><\/td><\/tr><tr><td width=\"127\"><p>Annotazioni<\/p><\/td><td width=\"523\"><p>Il progetto, iniziato nel 2014, \u00e8 realizzato con il sostegno della Commissione Europea; la risorsa \u00e8 pensata, in modo specifico, per chi opera nel settore alberghiero, nella ristorazione e nel commercio.<\/p><p>Questa risorsa, purtroppo, non \u00e8 pi\u00f9 accessibile, se non in forma parziale e frammentaria, al momento dell\u2019ultima verifica del funzionamento dei siti e delle risorse presentate nel repertorio.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab3\" class=\"uc_ac_box elementor-repeater-item-e91ce41 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Russian for Everyone \u2013 Learn Russian Online<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"126\"><p>Nome<\/p><\/td><td width=\"524\"><p><strong><em>Russian for Everyone \u2013 Learn Russian Online<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"126\"><p>Indirizzo Internet<\/p><\/td><td width=\"524\"><p><a href=\"http:\/\/www.russianforeveryone.com\/\">http:\/\/www.russianforeveryone.com\/<\/a><\/p><\/td><\/tr><tr><td width=\"126\"><p>Livello<\/p><\/td><td width=\"524\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"126\"><p>Parole chiave<\/p><\/td><td width=\"524\"><p><strong>Fonetica<\/strong>, grammatica, lessico, test di livello, giochi.<\/p><\/td><\/tr><tr><td width=\"126\"><p>Contenuti<\/p><\/td><td width=\"524\"><p>Schede grammaticali con esercizi, test di livello, giochi interattivi.<\/p><\/td><\/tr><tr><td width=\"126\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"524\"><p>Numerosi esempi, sempre supportati da un file audio e, occasionalmente, da immagini; esercizi e test per monitorare i progressi fatti dall\u2019apprendente; presenza di un forum in cui chiarire eventuali dubbi e di una sezione interamente dedicata a tabelle riepilogative che possono essere usate per ripassare i vari argomenti. Nella sezione <em>Phrasebook<\/em> si trovano idee e suggerimenti per incoraggiare la produzione scritta individuale. Presenza di esercizi, test e giochi.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab4\" class=\"uc_ac_box elementor-repeater-item-e31426a \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Russian Language Online Tutorial and Russian Phrasebook<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>Russian Language Online Tutorial and Russian Phrasebook<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"http:\/\/waytorussia.net\/WhatIsRussia\/Russian.html\">http:\/\/waytorussia.net\/WhatIsRussia\/Russian.html<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p><strong>Fonetica<\/strong>, lessico, turismo, cultura, civilt\u00e0 russa.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>Dizionario con file audio di supporto, traslitterazione, pronuncia; pratico tutorial per imparare a scrivere in corsivo.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>Lessico ricco, suddiviso secondo i principali ambiti di utilizzo; file audio per facilitare la corretta pronuncia dei vocaboli; la struttura schematica delle sezioni permette una rapida ed efficace consultazione; presenza di un forum in cui scambiare opinioni e chiarire eventuali dubbi con altri utenti.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>Molte informazioni di carattere pratico, rielaborate in un contesto d\u2019apprendimento, per soggiornare e vivere in Russia.<\/p><p>Questa risorsa, al momento dell\u2019ultima verifica, non risulta pi\u00f9 disponibile al link sopra riportato che, oggi, non \u00e8 pi\u00f9 attivo e non reindirizzato a una versione aggiornata.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab5\" class=\"uc_ac_box elementor-repeater-item-cf5b9f6 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Sajt Anny Strelkovskoj (for those who learn Russian)<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"123\"><p>Nome<\/p><\/td><td width=\"546\"><p><strong><em>Sajt Anny Strelkovskoj (for those who learn Russian)<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"123\"><p>Indirizzo Internet<\/p><\/td><td width=\"546\"><p><a href=\"http:\/\/annagroup.ru\/index\/russian_for_beginners\/0-165\">http:\/\/annagroup.ru\/index\/russian_for_beginners\/0-165<\/a><\/p><\/td><\/tr><tr><td width=\"123\"><p>Livello<\/p><\/td><td width=\"546\"><p>Principianti assoluti, A1, A2, B1<\/p><\/td><\/tr><tr><td width=\"123\"><p>Parole chiave<\/p><\/td><td width=\"546\"><p><strong>Fonetica<\/strong>, alfabeto russo, lessico, aspetto del verbo, verbi di moto, participi e gerundi, comprensione del testo, orale e scritto<\/p><\/td><\/tr><tr><td width=\"123\"><p>Contenuti<\/p><\/td><td width=\"546\"><p>La risorsa comprende le seguenti macrosezioni: <em>Pagina principale<\/em>,<em> Russian from Russia<\/em>,<em> Russian for Beginners<\/em>,<em> Glagoly dvi<\/em><em>\u017e<\/em><em>enija<\/em>,<em> Neobchodimye frazy<\/em>,<em> Slovo nedeli<\/em>,<em> My <\/em><em>\u010d<\/em><em>itaem<\/em>,<em> Upra<\/em><em>\u017enenija<\/em>, <em>Upra<\/em><em>\u017enenija o Rossii<\/em>,<em> Krossvordy<\/em>,<em> Grammatika<\/em>,<em> Gruppy<\/em>,<em> Video i slajd-\u0161<\/em><em>ou<\/em>,<em> Interesnaja nedelja<\/em>,<em> Skorogovorki<\/em>,<em> Videoslovari<\/em>,<em> Poleznye ssylki<\/em>.<\/p><\/td><\/tr><tr><td width=\"123\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"546\"><p>Presenza di abbondante materiale audio e video; ricchezza del materiale e variet\u00e0 delle attivit\u00e0 proposte.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n  <\/div>\n<\/div>\n\t\t\t<!-- end Content Accordion -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48d413a elementor-widget elementor-widget-spacer\" data-id=\"48d413a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dc95b5 elementor-widget elementor-widget-text-editor\" data-id=\"1dc95b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Competenza morfosintattica<\/strong><\/h3><p>Tra le varie risorse disponibili in rete, per lo sviluppo della <strong>competenza morfosintattica<\/strong>, in particolare, segnaliamo:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-863a045 elementor-widget elementor-widget-ucaddon_content_accordion\" data-id=\"863a045\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_content_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- start Content Accordion -->\n\n\t\t\t<style type=\"text\/css\">\/* widget: Content Accordion *\/\n\n\n\n#uc_content_accordion_elementor_863a045 *{\n  box-sizing: border-box;\n}\n\n#uc_content_accordion_elementor_863a045 .ue_heading_title{\n  margin:0;\n  flex-grow:1;\n  display:flex;\n  flex-direction:row;\n}\n\n#uc_content_accordion_elementor_863a045 .uc_container .uc-heading{\n\tdisplay:flex;\n    align-items:center;\n\toverflow:hidden;\n\tcursor:pointer;  \n}\n\n#uc_content_accordion_elementor_863a045 .uc_container .uc_content{\n    display:none;\n}\n\n#uc_content_accordion_elementor_863a045 .uc_container .uc-heading span.ue_accordion_icon{\n\tdisplay:flex;\n    align-items:center;\n   \tjustify-content:center;\n    flex-grow:0;\n    flex-shrink:0;\n}\n\n#uc_content_accordion_elementor_863a045 .uc_ac_box.uc-item-active span.uc_dactive{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_863a045 .uc_ac_box:not(.uc-item-active) span.uc_active{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_863a045 span.ue_accordion_icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_content_accordion_elementor_863a045 .uc_container .uc_btn {\n    text-align: center;\n    display: inline-block;\n    text-decoration: none;\n    transition: ease-in-out all 0.25s;\n}\n\n#uc_content_accordion_elementor_863a045 .ue-item-image img{\n  width:100%;\n  display:block;\n  object-fit:cover;\n}\n\n<\/style>\n\n\t\t\t<div class=\"uc_material_accordion  \"  id=\"uc_content_accordion_elementor_863a045\"  data-name=\"\" data-scroll=\"off\" data-offset=\"0\" data-closeothers=\"true\" data-set-hash=\"false\" data-transition-duration=\"400\" >\n  <div class=\"uc_container uc-items-wrapper\">\n    \n\n\n\n\n<div id=\"#ue-tab1\" class=\"uc_ac_box elementor-repeater-item-7392a35 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Revita<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"539\"><p><strong><em>Revita<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"539\"><p><u><a href=\"https:\/\/revita.cs.helsinki.fi\/welcome\">https:\/\/revita.cs.helsinki.fi\/welcome<\/a><\/u><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"539\"><p>Da A1+ a C1+<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"539\"><p><strong>Morfosintassi<\/strong>, fonetica, lessico, comprensione del testo, test, cruciverba.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"539\"><p>Testi, esercizi, test, <em>flashcard<\/em>, cruciverba, quiz; la piattaforma \u00e8 in grado di creare attivit\u00e0 ed esercizi a partire sia dai testi in essa presenti sia da quelli inseriti dagli utenti.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"539\"><p>La risorsa consente un apprendimento attivo e personalizzato della lingua, presentando allo studente esercizi di difficolt\u00e0 sempre calibrata; consente, inoltre, il tracciamento dei progressi fatti dallo studente e l\u2019analisi dei risultati degli esercizi svolti che vengono mostrati nella sezione \u00ab<em>Statistiche avanzate\u00bb<\/em>. Possibilit\u00e0 di esercitare la grammatica attivamente, basandosi su testi autentici; esercizi di morfosintassi a riempimento e completamento, esercizi lessicali a scelta multipla; possibilit\u00e0 di effettuare test generati automaticamente dalla piattaforma in cui gli <em>item <\/em>vengono proposti a partire dalla risposta data dallo studente all\u2019<em>item <\/em>precedente (test adattivi) per stabilire il livello di competenza linguistica in entrata. La risorsa permette di sviluppare la competenza fonologica, lessicale, morfosintattica e testuale; per ogni testo o esercizio viene indicato l\u2019elenco degli argomenti sui quali ci si esercita; batteria di testi e test organizzati a seconda del livello di difficolt\u00e0; attivit\u00e0 di comprensione del testo; <em>flashcard <\/em>per lo sviluppo della competenza lessicale; cruciverba generati automaticamente dalla risorsa con le parole nuove per l\u2019utente; facilit\u00e0 d\u2019uso della risorsa. La risorsa non \u00e8 fruibile da parte di apprendenti principianti assoluti.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"539\"><p>La piattaforma \u00e8 stata sviluppata presso il Language Learning Lab dell\u2019Universit\u00e0 di Helsinki e il sistema computazionale \u00e8 in continuo aggiornamento. L\u2019interfaccia della piattaforma \u00e8 plurilingue (finlandese, russo, inglese, italiano, svedese).<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab2\" class=\"uc_ac_box elementor-repeater-item-6d5e5c0 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Study Languages Online. Let\u2019s learn Russian online<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"520\"><p><strong><em>Study Languages Online. Let\u2019s learn Russian online<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"520\"><p><a href=\"http:\/\/www.study-languages-online.com\/index.html\">http:\/\/www.study-languages-online.com\/index.html<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"520\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"520\"><p><strong>Morfosintassi<\/strong>, esercizi interattivi, test, fonetica, testi per la lettura, lessico, giochi, turismo.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"520\"><p>Schede grammaticali dettagliate, svariati esercizi e test di livello; testi di lettura su vari argomenti (citt\u00e0 russe, cucina russa ecc.); numerosi dialoghi e abbondante materiale relativo a varie situazioni di vita quotidiana (all\u2019aeroporto, al ristorante, in albergo ecc.).<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"520\"><p>10 lezioni (<em>In the airport, Transport, At the hotel, In the street, Sightseeing, Shopping, At the restaurant, At the drugstore, Currency exchange, Internet &amp; Phone<\/em>) con dialoghi relativi a situazioni tipiche all\u2019interno di ristoranti, hotel negozi ecc. ed esercizi interattivi; test di livello per controllare i progressi fatti. Ogni lezione contiene supporti audio, utili per la pronuncia e per la fonetica; lessico ampio. Presenza di attivit\u00e0 ludiche che rendono pi\u00f9 piacevole il primo impatto con la lingua.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab3\" class=\"uc_ac_box elementor-repeater-item-0d89e76 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Lezioni di Russo<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"123\"><p>Nome<\/p><\/td><td width=\"527\"><p><strong><em>Lezioni di Russo<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"123\"><p>Indirizzo Internet<\/p><\/td><td width=\"527\"><p><a href=\"http:\/\/www.nassaro.com\/index.php\/lezioni-di-russo\">http:\/\/www.nassaro.com\/index.php\/lezioni-di-russo<\/a><\/p><\/td><\/tr><tr><td width=\"123\"><p>Livello<\/p><\/td><td width=\"527\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"123\"><p>Parole chiave<\/p><\/td><td width=\"527\"><p><strong>Morfosintassi<\/strong>, comparativi, superlativi, aggettivi, aspetto imperfettivo e perfettivo, preposizioni.<\/p><\/td><\/tr><tr><td width=\"123\"><p>Contenuti<\/p><\/td><td width=\"527\"><p>Schede e tabelle grammaticali.<\/p><\/td><\/tr><tr><td width=\"123\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"527\"><p>Il corso \u00e8 in lingua italiana; completa e dettagliata la sezione sui comparativi e superlativi; trattazione esaustiva di participi e gerundi.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab4\" class=\"uc_ac_box elementor-repeater-item-dc3d990 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Russian Language Lessons \u2013 Learn Russian For Fre<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"126\"><p>Nome<\/p><\/td><td width=\"524\"><p><strong><em>Russian Language Lessons \u2013 Learn Russian For Free<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"126\"><p>Indirizzo Internet<\/p><\/td><td width=\"524\"><p><a href=\"http:\/\/www.russianlessons.net\/\">http:\/\/www.russianlessons.net\/<\/a><\/p><\/td><\/tr><tr><td width=\"126\"><p>Livello<\/p><\/td><td width=\"524\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"126\"><p>Parole chiave<\/p><\/td><td width=\"524\"><p><strong>Morfosintassi<\/strong>, lessico, frasario, turismo.<\/p><\/td><\/tr><tr><td width=\"126\"><p>Contenuti<\/p><\/td><td width=\"524\"><p>Numerose e dettagliate schede grammaticali con esercizi e file audio, vocabolario.<\/p><\/td><\/tr><tr><td width=\"126\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"524\"><p>La sezione dedicata alla lettura propone il romanzo \u00ab<em>Delitto e Castigo\u00bb <\/em>con traduzione a fronte in inglese; la sezione <em>Audio Articles<\/em>, molto ben curata, contiene molti articoli, spesso accompagnati da file audio, molto utili per la fonetica, di diversa difficolt\u00e0 che trattano argomenti di sicuro interesse per l\u2019apprendente (sport, cucina, usi e costumi, globalizzazione ecc.); utile sezione dedicata ai <em>tool <\/em>online (Dizionario Inglese-Russo, tastiera russa virtuale e un programma per la traslitterazione) e a svariate risorse.<\/p><\/td><\/tr><tr><td width=\"126\"><p>Annotazioni<\/p><\/td><td width=\"524\"><p>Possibilit\u00e0 di commentare gli articoli presenti nella risorsa utilizzando il forum di discussione; il sito \u00e8 in lingua inglese.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab5\" class=\"uc_ac_box elementor-repeater-item-8783896 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Beginning Russian Grammar<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"125\"><p>Nome<\/p><\/td><td width=\"525\"><p><strong><em>Beginning Russian Grammar<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"125\"><p>Indirizzo Internet<\/p><\/td><td width=\"525\"><p><a href=\"http:\/\/russian.cornell.edu\/grammar\/\">http:\/\/russian.cornell.edu\/grammar\/<\/a><\/p><\/td><\/tr><tr><td width=\"125\"><p>Livello<\/p><\/td><td width=\"525\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"125\"><p>Parole chiave<\/p><\/td><td width=\"525\"><p><strong>Morfosintassi<\/strong>, russo\/inglese, verbi, casi, preposizioni.<\/p><\/td><\/tr><tr><td width=\"125\"><p>Contenuti<\/p><\/td><td width=\"525\"><p>Schede grammaticali complete e dettagliate.<\/p><\/td><\/tr><tr><td width=\"125\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"525\"><p>Completezza della grammatica e analisi dettagliata di argomenti che spesso risultano difficili per gli apprendenti; i temi trattati sono suddivisi in base al livello di difficolt\u00e0.<\/p><\/td><\/tr><tr><td width=\"125\"><p>Annotazioni<\/p><\/td><td width=\"525\"><p>Il sito \u00e8 in lingua inglese.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab6\" class=\"uc_ac_box elementor-repeater-item-b27ae8d \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">English and Russian Grammar for Students of Russian<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"125\"><p>Nome<\/p><\/td><td width=\"525\"><p><strong><em>English and Russian Grammar for Students of Russian<\/em><\/strong><\/p><p><strong><em>\u00a0<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"125\"><p>Indirizzo Internet<\/p><\/td><td width=\"525\"><p><a href=\"http:\/\/www.du.edu\/langlit\/russian\/grammar.htm\">http:\/\/www.du.edu\/langlit\/russian\/grammar.htm<\/a><\/p><\/td><\/tr><tr><td width=\"125\"><p>Livello<\/p><\/td><td width=\"525\"><p>A1<\/p><\/td><\/tr><tr><td width=\"125\"><p>Parole chiave<\/p><\/td><td width=\"525\"><p><strong>Morfosintassi<\/strong>, esercizi, traslitterazione, verbo, morfologia.<\/p><\/td><\/tr><tr><td width=\"125\"><p>Contenuti<\/p><\/td><td width=\"525\"><p>Schede grammaticali con esercizi ed esempi.<\/p><\/td><\/tr><tr><td width=\"125\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"525\"><p>Il corso riassume schematicamente e brevemente tutte le nozioni base della grammatica russa, anche se sono omessi argomenti importanti (ad esempio, numerali e verbi riflessivi).<\/p><\/td><\/tr><tr><td width=\"125\"><p>Annotazioni<\/p><\/td><td width=\"525\"><p>I link segnalati sono particolarmente utili per una panoramica sulla civilt\u00e0 e sulla cultura russa contemporanea.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab7\" class=\"uc_ac_box elementor-repeater-item-5df8713 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Learn Russian \u2013 Russian Language Lessons and Culture<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>Learn Russian \u2013 Russian Language Lessons and Culture<\/em><\/strong><\/p><p><strong><em>\u00a0<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"http:\/\/learningrussian.net\/\">http:\/\/learningrussian.net\/<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p><strong>Morfosintassi<\/strong>, letteratura e cultura, video, audio, forum, traduttore online.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>Si tratta di un corso per principianti, strutturato in otto lezioni, che presenta schede grammaticali, file audio e video, classici della letteratura russa con traduzione a fronte in inglese.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>Schede grammaticali non molto articolate ma con spiegazioni chiare, precise e sintetiche; dizionario online molto valido; lessico ricco e vario; presenza di file audio e video e di un forum ben strutturato in cui fare commenti e domande su ogni lezione.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>Il sito \u00e8 realizzato in lingua inglese. La struttura di ogni lezione \u00e8 la medesima (V<em>ocabulary, Listening, Grammar) <\/em>e le spiegazioni sono in inglese.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab8\" class=\"uc_ac_box elementor-repeater-item-3781260 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">MasterRussian.com<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"125\"><p>Nome<\/p><\/td><td width=\"525\"><p><strong><em>MasterRussian.com<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"125\"><p>Indirizzo Internet<\/p><\/td><td width=\"525\"><p><a href=\"http:\/\/masterrussian.com\/blprevious.shtml\">http:\/\/masterrussian.com\/blprevious.shtml<\/a><\/p><\/td><\/tr><tr><td width=\"125\"><p>Livello<\/p><\/td><td width=\"525\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"125\"><p>Parole chiave<\/p><\/td><td width=\"525\"><p><strong>Morfosintassi<\/strong>, lessico, cultura, turismo.<\/p><\/td><\/tr><tr><td width=\"125\"><p>Contenuti<\/p><\/td><td width=\"525\"><p>Il sito in lingua inglese si rivolge a studenti di ogni livello; non offre un corso vero e proprio, ma le schede grammaticali sono ben strutturate e con numerosi esempi. Il corso \u00e8 suddiviso nelle seguenti sezioni principali: <em>Nouns<\/em>,<em> Pronouns<\/em>,<em> Cases<\/em>,<em> Adjectives<\/em>,<em> Verbs<\/em>,<em> Numerals<\/em>,<em> Tips and Advice<\/em>,<em> Vocabulary<\/em>,<em> How-To\u2019s<\/em>,<em> Product Review<\/em>.<\/p><\/td><\/tr><tr><td width=\"125\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"525\"><p>Grafica semplice, navigabilit\u00e0 abbastanza buona, discreta interattivit\u00e0; la sezione dedicata ai link utili (con collegamenti anche a siti di radio e TV russe) propone parecchie risorse molto valide per lo studio del russo; le schede grammaticali, pur essendo molto sintetiche e schematiche, non tralasciano concetti importanti; l\u2019ampia sezione dedicata al lessico risulta molto utile per ampliare il proprio vocabolario; vengono forniti numerosi esempi riguardo ai temi trattati; in ogni lezione presenza di un forum di discussione interattivo e di un\u2019apposita sezione in cui chiedere chiarimenti.<\/p><\/td><\/tr><tr><td width=\"125\"><p>Annotazioni<\/p><\/td><td width=\"525\"><p>La sezione <em>Tips and Advice <\/em>fornisce all\u2019apprendente alcuni suggerimenti pratici per l\u2019apprendimento del russo, mentre <em>How-To\u2019s <\/em>spiega, ad esempio, cosa fare nel caso in cui non si riescano a visualizzare sullo schermo del computer i caratteri cirillici. La risorsa si distingue per un discreto grado di interattivit\u00e0.<\/p><p>Si tratta di un sito storico (attivo dal 2001).<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab9\" class=\"uc_ac_box elementor-repeater-item-c728d88 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">PushkinOnLine<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>PushkinOnLine<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"http:\/\/www.pushkininstitute.ru\">www.pushkininstitute.ru<\/a><\/p><p><a href=\"https:\/\/pushkininstitute.ru\/?locale=en\">https:\/\/pushkininstitute.ru\/?locale=en<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>Per apprendenti di tutti i livelli di competenza linguistica.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p><strong>Morfosintassi<\/strong>, lessico, attivit\u00e0 interattive<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>Ogni lezione consiste in una vera sessione di allenamento; schede grammaticali complete ed esaustive per prendere dimestichezza con l\u2019uso dei casi.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>Si tratta di una risorsa online particolarmente ricca e completa<em>, <\/em>realizzata dal <em>Pushkin State Russian Language Institute<\/em>, offre corsi costruiti su un sistema modulare; i temi trattati sono suddivisi in base al livello di difficolt\u00e0, tutti i materiali sono divisi per livello; ampia scelta di materiale audio e video (spezzoni autentici di film e trasmissioni televisive, cartoni animati, interviste ecc.); possibilit\u00e0 di esercitare tutte le abilit\u00e0 previste dal sistema di certificazione <em>TRKI<\/em>.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>\u00c8 sufficiente effettuare la registrazione al portale \u00ab<em>\u041e\u0431\u0440\u0430\u0437\u043e\u0432\u0430\u043d\u0438\u0435<\/em> <em>\u043d\u0430<\/em> <em>\u0440\u0443\u0441\u0441\u043a\u043e\u043c<\/em><em>\u00bb<\/em> per accedere a un corso completo dal livello A1 al livello C2. Possibilit\u00e0 di fare un test per determinare il proprio livello di competenza linguistica. Possibilit\u00e0 di seguire webinar di letteratura e cultura tenuti dai professori dell\u2019Istituto.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab10\" class=\"uc_ac_box elementor-repeater-item-4b5314b \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Russian for Beginners<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>Russian for Beginners<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"http:\/\/www.open-of-course.org\/courses\/course\/view.php?id=37\">http:\/\/www.open-of-course.org\/courses\/course\/view.php?id=37<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>A1<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p><strong>Morfosintassi<\/strong>, lessico.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>Schede grammaticali con esercizi<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>Semplicit\u00e0 delle spiegazioni, supportate da esempi chiari e di facile comprensione; presenza di un forum in cui confrontarsi con altri studenti o ricevere eventuali spiegazioni; le lezioni, presentate in modo molto semplice, sono un supporto ideale per muovere i primi passi nello studio di questa lingua.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>Il sito \u00e8 in lingua inglese.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n  <\/div>\n<\/div>\n\t\t\t<!-- end Content Accordion -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-918e0fc elementor-widget elementor-widget-spacer\" data-id=\"918e0fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4976e07 elementor-widget elementor-widget-text-editor\" data-id=\"4976e07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Competenza testuale<\/strong><\/h3><p>Per lo sviluppo della <strong>competenza testuale<\/strong><a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a> si segnalano giornali e riviste russe online che sono una fonte inesauribile di materiale su attualit\u00e0, politica, economia, cultura, societ\u00e0, sport e ben si prestano a differenti tipi di indagini:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ef355a elementor-widget elementor-widget-ucaddon_content_accordion\" data-id=\"3ef355a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_content_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- start Content Accordion -->\n\n\t\t\t<style type=\"text\/css\">\/* widget: Content Accordion *\/\n\n\n\n#uc_content_accordion_elementor_3ef355a *{\n  box-sizing: border-box;\n}\n\n#uc_content_accordion_elementor_3ef355a .ue_heading_title{\n  margin:0;\n  flex-grow:1;\n  display:flex;\n  flex-direction:row;\n}\n\n#uc_content_accordion_elementor_3ef355a .uc_container .uc-heading{\n\tdisplay:flex;\n    align-items:center;\n\toverflow:hidden;\n\tcursor:pointer;  \n}\n\n#uc_content_accordion_elementor_3ef355a .uc_container .uc_content{\n    display:none;\n}\n\n#uc_content_accordion_elementor_3ef355a .uc_container .uc-heading span.ue_accordion_icon{\n\tdisplay:flex;\n    align-items:center;\n   \tjustify-content:center;\n    flex-grow:0;\n    flex-shrink:0;\n}\n\n#uc_content_accordion_elementor_3ef355a .uc_ac_box.uc-item-active span.uc_dactive{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_3ef355a .uc_ac_box:not(.uc-item-active) span.uc_active{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_3ef355a span.ue_accordion_icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_content_accordion_elementor_3ef355a .uc_container .uc_btn {\n    text-align: center;\n    display: inline-block;\n    text-decoration: none;\n    transition: ease-in-out all 0.25s;\n}\n\n#uc_content_accordion_elementor_3ef355a .ue-item-image img{\n  width:100%;\n  display:block;\n  object-fit:cover;\n}\n\n<\/style>\n\n\t\t\t<div class=\"uc_material_accordion  \"  id=\"uc_content_accordion_elementor_3ef355a\"  data-name=\"\" data-scroll=\"off\" data-offset=\"0\" data-closeothers=\"true\" data-set-hash=\"false\" data-transition-duration=\"400\" >\n  <div class=\"uc_container uc-items-wrapper\">\n    \n\n\n\n\n<div id=\"#ue-tab1\" class=\"uc_ac_box elementor-repeater-item-0a96546 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">\u0410\u0420\u0413\u0423\u041c\u0415\u041d\u0422\u042b \u0418 \u0424\u0410\u041a\u0422\u042b AIF.RU<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"127\"><p>Nome<\/p><\/td><td width=\"523\"><p><strong><em>\u0430\u0440\u0433\u0443\u043c\u0435\u043d\u0442\u044b \u0438 \u0424\u0430\u043a\u0442\u044b <\/em><\/strong><strong><em>aif<\/em><\/strong><strong><em>.<\/em><\/strong><strong><em>ru<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"127\"><p>Indirizzo Internet<\/p><\/td><td width=\"523\"><p><a href=\"http:\/\/www.aif.ru\">www.aif.ru<\/a><\/p><\/td><\/tr><tr><td width=\"127\"><p>Contenuti<\/p><\/td><td width=\"523\"><p>Attualit\u00e0, politica, economia, cultura, sport ecc.; trattasi di uno dei pi\u00f9 diffusi e popolari settimanali russi.<\/p><\/td><\/tr><tr><td width=\"127\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"523\"><p>Tramite Telegram Messenger<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>, \u00e8 possibile ricevere sul proprio dispositivo mobile, velocemente, gratuitamente e senza pubblicit\u00e0 gli articoli pi\u00f9 interessanti (<em>\u0410\u0438\u0424<\/em> <em>\u0432<\/em><em> Telegram<\/em>).<\/p><\/td><\/tr><tr><td width=\"127\"><p>Annotazioni<\/p><\/td><td width=\"523\"><p>Il primo numero viene pubblicato nel 1978. Dal 1980 diventa un settimanale che, nel corso degli anni, vince molti premi, russi e internazionali. Nel 1990, <em>Argumenty i Fakty<\/em> viene inserito nel Guinness Book of Records, l\u2019annuale raccolta dei record mondiali, per la pi\u00f9 ampia diffusione rispetto a qualsiasi altro settimanale, con 33400 copie nel mondo. Nel 1999 una pietra con il logo \u00abAiF\u00bb viene collocata sulla pavimentazione dell\u2019Arbat, via pedonale moscovita, resa celebre, in particolare, dai versi di Bulat \u0160alvovi\u010d Okud\u017eava.<\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab2\" class=\"uc_ac_box elementor-repeater-item-f8c3f99 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">\u0418\u0417\u0412\u0415\u0421\u0422\u0418\u042f<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"127\"><p>Nome<\/p><\/td><td width=\"523\"><p><strong>\u0438\u0437\u0432\u0435\u0441\u0442\u0438\u044f<\/strong><\/p><\/td><\/tr><tr><td width=\"127\"><p>Indirizzo Internet<\/p><\/td><td width=\"523\"><p><a href=\"http:\/\/www.izvestia.ru\">www.izvestia.ru<\/a><\/p><\/td><\/tr><tr><td width=\"127\"><p>Contenuti<\/p><\/td><td width=\"523\"><p>Attualit\u00e0, politica, economia, cultura, turismo, sport, notizie dal mondo ecc.<\/p><\/td><\/tr><tr><td width=\"127\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"523\"><p>Il men\u00f9, riportato in cima alla pagina iniziale, permette di selezionare agevolmente le macrosezioni del sito (\u041d\u043e\u0432\u043e\u0441\u0442\u0438, \u0421\u0442\u0430\u0442\u044c\u0438, \u041b\u043e\u043d\u0433\u0440\u0438\u0434\u044b, \u041c\u043d\u0435\u043d\u0438\u044f, \u0424\u043e\u0442\u043e, \u0412\u0438\u0434\u0435\u043e, \u0420\u0443\u0431\u0440\u0438\u043a\u0438); cliccando sul pulsante \u0441\u043a\u0430\u0447\u0430\u0442\u044c pdf, \u00e8 possibile scaricare immediatamente sul proprio dispositivo il numero del giornale in formato .pdf.<\/p><\/td><\/tr><tr><td width=\"127\"><p>Annotazioni<\/p><\/td><td width=\"523\"><p>Il quotidiano russo <em>\u0418\u0437\u0432\u0435\u0441\u0442\u0438\u044f<\/em>, fondato a San Pietroburgo, viene pubblicato per la prima volta il 13 marzo 1917. \u00c8 uno dei quotidiani di pi\u00f9 antica fondazione in Russia, nonch\u00e9 uno dei pi\u00f9 diffusi e famosi. La sua sede attuale \u00e8 a Mosca e la tiratura \u00e8 di 234.500 copie.<\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab3\" class=\"uc_ac_box elementor-repeater-item-62eacab \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">LENTA.RU<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"127\"><p>Nome<\/p><\/td><td width=\"523\"><p><strong>lenta.ru<\/strong><\/p><\/td><\/tr><tr><td width=\"127\"><p>Indirizzo Internet<\/p><\/td><td width=\"523\"><p><a href=\"https:\/\/lenta.ru\">https:\/\/lenta.ru<\/a><\/p><\/td><\/tr><tr><td width=\"127\"><p>Contenuti<\/p><\/td><td width=\"523\"><p>Notizie dalla Russia e dal mondo, articoli, fotografie, video di attualit\u00e0, scienza e tecnica, sport.<\/p><\/td><\/tr><tr><td width=\"127\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"523\"><p>Notizie 7 giorni a settimana, H24<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>. Facilit\u00e0 di reperimento delle informazioni, dal momento che, in ogni macrosezione, in un\u2019area evidenziata, collocata nella parte destra della pagina, sono riportate le ultime notizie (\u041f\u043e\u0441\u043b\u0435\u0434\u043d\u0438\u0435 \u043d\u043e\u0432\u043e\u0441\u0442\u0438), mentre, secondo le stesse modalit\u00e0, in ogni sottosezione compaiono le notizie principali (\u0413\u043b\u0430\u0432\u043d\u044b\u0435 \u043d\u043e\u0432\u043e\u0441\u0442\u0438).<\/p><\/td><\/tr><tr><td width=\"127\"><p>Annotazioni<\/p><\/td><td width=\"523\"><p>Lenta.ru (<a href=\"https:\/\/lenta.ru\">https:\/\/lenta.ru<\/a>) \u00e8 costituito dalle seguenti macrosezioni: \u0411\u044b\u0432\u0448\u0438\u0439 \u0421\u0421\u0421\u0420, \u041d\u0430\u0443\u043a\u0430 \u0438 \u0442\u0435\u0445\u043d\u0438\u043a\u0430, \u0421\u043f\u043e\u0440\u0442, \u0418\u0437 \u0436\u0438\u0437\u043d\u0438, \u041c\u0438\u0440, \u0420\u043e\u0441\u0441\u0438\u044f. Ogni macrosezione, a sua volta, \u00e8 suddivisa in alcune sottosezioni. In dettaglio, \u0411\u044b\u0432\u0448\u0438\u0439 \u0421\u0421\u0421\u0420 \u00e8 costituita da \u041f\u0440\u0438\u0431\u0430\u043b\u0442\u0438\u043a\u0430, \u0423\u043a\u0440\u0430\u0438\u043d\u0430, \u0411\u0435\u043b\u043e\u0440\u0443\u0441\u0441\u0438\u044f, \u041c\u043e\u043b\u0434\u0430\u0432\u0438\u044f, \u041a\u0430\u0432\u043a\u0430\u0437, \u041a\u0430\u0437\u0430\u0445\u0441\u0442\u0430\u043d, \u0421\u0440\u0435\u0434\u043d\u044f\u044f \u0410\u0437\u0438\u044f; \u041d\u0430\u0443\u043a\u0430 \u0438 \u0442\u0435\u0445\u043d\u0438\u043a\u0430 da \u041d\u0430\u0443\u043a\u0430, \u0416\u0438\u0437\u043d\u044c, \u041a\u043e\u0441\u043c\u043e\u0441, \u041e\u0440\u0443\u0436\u0438\u0435, \u0418\u0441\u0442\u043e\u0440\u0438\u044f, \u0422\u0435\u0445\u043d\u0438\u043a\u0430, \u0413\u0430\u0434\u0436\u0435\u0442\u044b, \u0418\u0433\u0440\u044b, \u0421\u043e\u0444\u0442; \u0421\u043f\u043e\u0440\u0442 da \u0424\u0443\u0442\u0431\u043e\u043b, \u0411\u043e\u043a\u0441 \u0438 \u041c\u041c\u0410, \u0427\u041c-2018, \u0417\u0438\u043c\u043d\u0438\u0435 \u0432\u0438\u0434\u044b, \u041b\u0435\u0442\u043d\u0438\u0435 \u0432\u0438\u0434\u044b, \u0425\u043e\u043a\u043a\u0435\u0439, \u0410\u0432\u0442\u043e, \u041e\u0418-2018; \u0418\u0437 \u0436\u0438\u0437\u043d\u0438 da \u041b\u044e\u0434\u0438, \u0417\u0432\u0435\u0440\u0438, \u0412\u0435\u0449\u0438, \u0415\u0434\u0430, \u0421\u043e\u0431\u044b\u0442\u0438\u044f, \u041f\u0440\u043e\u0438\u0441\u0448\u0435\u0441\u0442\u0432\u0438\u044f, \u0414\u043e\u0441\u0442\u0438\u0436\u0435\u043d\u0438\u044f; \u041c\u0438\u0440 da \u041f\u043e\u043b\u0438\u0442\u0438\u043a\u0430, \u041e\u0431\u0449\u0435\u0441\u0442\u0432\u043e, \u041f\u0440\u043e\u0438\u0441\u0448\u0435\u0441\u0442\u0432\u0438\u044f, \u0421\u0442\u0440\u0430\u043d\u043e\u0432\u0435\u0434\u0435\u043d\u0438\u0435, \u0412\u044b\u0431\u043e\u0440\u044b, \u041a\u043e\u043d\u0444\u043b\u0438\u043a\u0442\u044b, \u041f\u0440\u0435\u0441\u0442\u0443\u043f\u043d\u043e\u0441\u0442\u044c; \u0420\u043e\u0441\u0441\u0438\u044f da \u041f\u043e\u043b\u0438\u0442\u0438\u043a\u0430, \u041e\u0431\u0449\u0435\u0441\u0442\u0432\u043e, \u041f\u0440\u043e\u0438\u0441\u0448\u0435\u0441\u0442\u0432\u0438\u044f, \u0420\u0435\u0433\u0438\u043e\u043d\u044b, 69-\u043f\u0430\u0440\u0430\u043b\u043b\u0435\u043b\u044c, \u041a\u0440\u044b\u043c, \u041c\u043e\u0441\u043a\u0432\u0430, \u041a\u0430\u0442\u0430\u0441\u0442\u0440\u043e\u0444\u044b.<\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab4\" class=\"uc_ac_box elementor-repeater-item-ec1bdd4 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">\u041d\u0413 \u041d\u0415\u0417\u0410\u0412\u0418\u0421\u0418\u041c\u0410\u042f \u0413\u0410\u0417\u0415\u0422\u0410<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"127\"><p>Nome<\/p><\/td><td width=\"523\"><p><strong>\u041d\u0413 \u043d\u0435\u0437\u0430\u0432\u0438\u0441\u0438\u043c\u0430\u044f \u0433\u0430\u0437\u0435\u0442\u0430<\/strong><\/p><\/td><\/tr><tr><td width=\"127\"><p>Indirizzo Internet<\/p><\/td><td width=\"523\"><p><a href=\"http:\/\/www.ng.ru\">www.ng.ru<\/a><\/p><\/td><\/tr><tr><td width=\"127\"><p>Contenuti<\/p><\/td><td width=\"523\"><p>Attualit\u00e0, politica, economica, cultura, scienza, salute, cinema ecc.<\/p><\/td><\/tr><tr><td width=\"127\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"523\"><p>Il materiale presente sul sito \u00e8 ben organizzato e i vari collegamenti, posti in cima alla pagina di apertura rimandano comodamente alle varie rubriche.<\/p><\/td><\/tr><tr><td width=\"127\"><p>Annotazioni<\/p><\/td><td width=\"523\"><p>Il quotidiano russo <em>Nezavisimaja gazeta<\/em> viene pubblicato per la prima volta il 21 dicembre del 1990. Si tratta di uno dei pi\u00f9 importanti quotidiani del periodo post-sovietico, con una tiratura media di 40000 copie. Oltre al quotidiano, vi sono supplementi dedicati a politica, societ\u00e0, cultura e arte.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab5\" class=\"uc_ac_box elementor-repeater-item-7040114 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Russnet, the Russian Language Network<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>Russnet, the Russian Language Network<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"http:\/\/www.russnet.org\">http:\/\/www.russnet.org<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>Da A1 a C1<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p>Lingua, cultura, letteratura, storia, scienze<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>La risorsa, in lingua inglese, offre moduli organizzati in diverse sezioni, cos\u00ec suddivise <em>Storia<\/em>,<em> Letteratura<\/em>,<em> Cultura<\/em>,<em> Scienze<\/em>, test online disponibili nella sezione <em>Assess<\/em>, abbondante materiale audio e video per allenare la comprensione orale e scritta.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>Studio della lingua (sezione <em>Learn<\/em>) collegato a svariati aspetti della cultura russa (sezione <em>Read<\/em>), numerosi collegamenti a siti utili.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>Originariamente finanziato in parte da <em>Ford Foundation<\/em>, <em>Russnet <\/em>\u00e8 un progetto <em>dell\u2019American Councils for International Education<\/em>.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab6\" class=\"uc_ac_box elementor-repeater-item-5440be0 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Prezidentskaja biblioteka<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>Prezidentskaja biblioteka<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"https:\/\/www.prlib.ru\/\">https:\/\/www.prlib.ru\/<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>Per apprendenti di livello intermedio e avanzato<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p>Lingua, storia e cultura russa<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>Lingua russa, storia russa, centro multimediale<\/p><p>Questa risorsa funziona come un archivio elettronico nazionale di copie digitali di articoli e pubblicazioni di diversi ambiti e discipline, nonch\u00e9 come centro multimediale. I materiali sono spesso accompagnati da immagini.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>Facilit\u00e0 nel reperire i materiali. Ampia raccolta di materiali.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>Questa risorsa pu\u00f2 essere consigliata non solo a insegnanti e traduttori, ma anche ai lettori come fonte di informazioni pi\u00f9 ampia.<\/p><p>Materiali presenti in lingua russa e in altre lingue straniere.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n  <\/div>\n<\/div>\n\t\t\t<!-- end Content Accordion -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-65a4672 e-con e-atomic-element e-flexbox-base e-65a4672-5d7b0ad \" data-id=\"65a4672\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"65a4672\">\n    \t\t<div class=\"elementor-element elementor-element-c6bd194 elementor-widget elementor-widget-text-editor\" data-id=\"c6bd194\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Competenza lessicale<\/strong><\/h3><p>Tra le varie risorse disponibili in rete, per lo sviluppo della <strong>competenza lessicale<\/strong>, in particolare, segnaliamo le seguenti, precisando altres\u00ec che inseriamo in questa sezione una risorsa specifica per l\u2019apprendimento e l\u2019insegnamento delle collocazioni, ossia delle combinazioni di parole rese tipiche dall\u2019uso, e della combinabilit\u00e0 dei vocaboli, giacch\u00e9 questo fenomeno linguistico, a nostro avviso particolarmente importante, molto spesso nella prassi didattica viene trascurato. Le collocazioni, infatti, restano un elemento marginale nell\u2019insegnamento e un fenomeno quasi sconosciuto agli apprendenti. In realt\u00e0, essendo un fenomeno dominante in tutte le lingue, sono fondamentali per una comunicazione naturale e fluida in una lingua seconda.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-702950e elementor-widget elementor-widget-ucaddon_content_accordion\" data-id=\"702950e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_content_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- start Content Accordion -->\n\n\t\t\t<style type=\"text\/css\">\/* widget: Content Accordion *\/\n\n\n\n#uc_content_accordion_elementor_702950e *{\n  box-sizing: border-box;\n}\n\n#uc_content_accordion_elementor_702950e .ue_heading_title{\n  margin:0;\n  flex-grow:1;\n  display:flex;\n  flex-direction:row;\n}\n\n#uc_content_accordion_elementor_702950e .uc_container .uc-heading{\n\tdisplay:flex;\n    align-items:center;\n\toverflow:hidden;\n\tcursor:pointer;  \n}\n\n#uc_content_accordion_elementor_702950e .uc_container .uc_content{\n    display:none;\n}\n\n#uc_content_accordion_elementor_702950e .uc_container .uc-heading span.ue_accordion_icon{\n\tdisplay:flex;\n    align-items:center;\n   \tjustify-content:center;\n    flex-grow:0;\n    flex-shrink:0;\n}\n\n#uc_content_accordion_elementor_702950e .uc_ac_box.uc-item-active span.uc_dactive{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_702950e .uc_ac_box:not(.uc-item-active) span.uc_active{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_702950e span.ue_accordion_icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_content_accordion_elementor_702950e .uc_container .uc_btn {\n    text-align: center;\n    display: inline-block;\n    text-decoration: none;\n    transition: ease-in-out all 0.25s;\n}\n\n#uc_content_accordion_elementor_702950e .ue-item-image img{\n  width:100%;\n  display:block;\n  object-fit:cover;\n}\n\n<\/style>\n\n\t\t\t<div class=\"uc_material_accordion  \"  id=\"uc_content_accordion_elementor_702950e\"  data-name=\"\" data-scroll=\"off\" data-offset=\"0\" data-closeothers=\"true\" data-set-hash=\"false\" data-transition-duration=\"400\" >\n  <div class=\"uc_container uc-items-wrapper\">\n    \n\n\n\n\n<div id=\"#ue-tab1\" class=\"uc_ac_box elementor-repeater-item-7dcfa21 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Internet Polyglot \u2013 Lezioni: Russo-Italiano<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"125\"><p>Nome<\/p><\/td><td width=\"543\"><p><strong><em>Internet Polyglot \u2013 Lezioni: Russo-Italiano<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"125\"><p>Indirizzo Internet<\/p><\/td><td width=\"543\"><p><a href=\"http:\/\/www.internetpolyglot.com\/\">http:\/\/www.internetpolyglot.com\/<\/a><\/p><\/td><\/tr><tr><td width=\"125\"><p>Livello<\/p><\/td><td width=\"543\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"125\"><p>Parole chiave<\/p><\/td><td width=\"543\"><p><strong>Lessico<\/strong>, giochi per memorizzare i vocaboli, dizionario per immagini, audio, forum di discussione.<\/p><\/td><\/tr><tr><td width=\"125\"><p>Contenuti<\/p><\/td><td width=\"543\"><p>Quarantaquattro lezioni, giochi interattivi di memoria e di traduzione, dizionario figurato con audio.<\/p><\/td><\/tr><tr><td width=\"125\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"543\"><p>Giochi interattivi di memoria e di traduzione, file audio e immagini per aiutare a memorizzare il lessico proposto, relativo agli ambiti pi\u00f9 importanti della vita quotidiana.<\/p><\/td><\/tr><tr><td width=\"125\"><p>Annotazioni<\/p><\/td><td width=\"543\"><p>Al momento dell\u2019ultima verifica relativa al funzionamento della risorsa \u00e8 stato notato che non risulta un redirect diretto e stabile della vecchia pagina a una nuova equivalente. Questa risorsa non \u00e8 accessibile da <em>Google<\/em>, bens\u00ec da <em>Yandex<\/em>.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab2\" class=\"uc_ac_box elementor-repeater-item-eccb2f9 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Language Guide<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"539\"><p><strong><em>Language Guide<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"539\"><p><a href=\"http:\/\/www.languageguide.org\/russian\/vocabulary\/\">http:\/\/www.languageguide.org\/russian\/vocabulary\/<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"539\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"539\"><p><strong>Lessico<\/strong>, dizionario per immagini, audio.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"539\"><p>Dizionario per immagini con supporto audio. Esercizi interattivi sull\u2019alfabeto.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"539\"><p>Il lessico \u00e8 vario e la suddivisione effettuata dagli autori permette di passare agevolmente da un tema all\u2019altro; la combinazione di immagini, scritto e audio risulta molto efficace per memorizzare i vocaboli.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab3\" class=\"uc_ac_box elementor-repeater-item-2bb208a \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Practice Russian<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"126\"><p>Nome<\/p><\/td><td width=\"543\"><p><strong><em>Practice Russian<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"126\"><p>Indirizzo Internet<\/p><\/td><td width=\"543\"><p><a href=\"http:\/\/www.practicerussian.com\/\">http:\/\/www.practicerussian.com<\/a><\/p><\/td><\/tr><tr><td width=\"126\"><p>Livello<\/p><\/td><td width=\"543\"><p>A1<\/p><\/td><\/tr><tr><td width=\"126\"><p>Parole chiave<\/p><\/td><td width=\"543\"><p><strong>Lessico<\/strong>, dizionario figurato, Frasario, giochi, musica, test di valutazione.<\/p><\/td><\/tr><tr><td width=\"126\"><p>Contenuti<\/p><\/td><td width=\"543\"><p>Materiale interattivo di tipo ludico per la didattica del russo online, esercizi, test di autovalutazione, giochi, liste di sostantivi, dialoghi.<\/p><\/td><\/tr><tr><td width=\"126\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"543\"><p>Ampia gamma di giochi; molto ben curata la sezione dedicata alla musica che propone un approccio originale per l\u2019apprendimento della lingua; dizionario figurato che pu\u00f2 essere di grande aiuto; buon livello di interattivit\u00e0.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab4\" class=\"uc_ac_box elementor-repeater-item-b5d3b50 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Russian on-line<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"539\"><p><strong><em>Russian on-line<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"539\"><p><a href=\"http:\/\/www.rus-on-line.ru\">http:\/\/www.rus-on-line.ru<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"539\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"539\"><p><strong>Lessico<\/strong>, fonetica, morfosintassi, tabelle riepilogative, esercizi<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"539\"><p>La risorsa \u00e8 costituita da cinque sezioni: <em>Bookshop of \u00abRussian on-line\u00bb <\/em>(in cui \u00e8 possibile acquistare dizionari di russo e materiale didattico multimediale); <em>Elementary <\/em>(A1) comprende le seguenti sottosezioni: corso introduttivo di fonetica, alfabeto russo, numerali, grammatica. Il materiale \u00e8 suddiviso in 44 schede, pratiche e ben strutturate, ognuna delle quali \u00e8 dedicata a un argomento specifico. Il livello <em>Basic <\/em>comprende due sottosezioni, ossia <em>Russian Grammar<\/em> che consta di 24 efficaci schede e <em>Let\u2019s speak Russian<\/em><em>! <\/em>che contiene 24 gruppi di parole, espressioni e frasi suddivise per argomento. La sezione <em>Exercises <\/em>propone un\u2019ampia scelta di esercizi, organizzati in due distinte sottosezioni <em>Elementary Level <\/em>e <em>Basic Level<\/em>. La sezione <em>Holidays <\/em>contiene interessanti informazioni sulle feste celebrate in Russia. Il vocabolario tematico visuale, invece, \u00e8 consultabile a pagamento.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"539\"><p>Il sito, che presenta ricco materiale audio, \u00e8 disponibile in due lingue (inglese e francese); il materiale \u00e8 organizzato in modo tale da consentirne la massima fruibilit\u00e0; facilit\u00e0 d\u2019utilizzo.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"539\"><p>La risorsa \u00e8 stata realizzata dal Prof. Sergej Fadeev, sulla base della sua pluriennale esperienza nell\u2019insegnamento della lingua russa a stranieri. Questo sito ha ottenuto a Mosca il premio \u00ab<em>Best in e-learning\u00bb<\/em> per la migliore risorsa internet dedicata agli stranieri che studiano la lingua russa e Sergej Fadeev \u00e8 stato premiato come \u00ab<em>Best creator of e-learning courses\u00bb.<\/em> Il sito \u00e8 in costante aggiornamento.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab5\" class=\"uc_ac_box elementor-repeater-item-d494c21 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Corso di russo \u2013 Principianti classe B 2007<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"539\"><p><strong><em>Corso di russo \u2013 Principianti classe B 2007<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"539\"><p><a href=\"https:\/\/corsodirusso.wordpress.com\/\">https:\/\/corsodirusso.wordpress.com\/<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"539\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"539\"><p><strong>Lessico<\/strong>, esercizi, turismo.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"539\"><p>Schede grammaticali, esercizi, lessico, collegamenti utili in vista di un viaggio in Russia, sezione denominata <em>News dalla Russia<\/em>.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"539\"><p>Al lessico viene prestata particolare attenzione e in ogni lezione sono proposti molti vocaboli; grazie al forum interattivo \u00e8 possibile ricevere chiarimenti e spiegazioni.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"539\"><p>Il corso \u00e8 in lingua italiana.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab6\" class=\"uc_ac_box elementor-repeater-item-2f40fe1 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">LR - Learn Russian<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"539\"><p><strong><em>LR - Learn Russian<\/em><\/strong><\/p><p><strong><em>\u00a0<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"539\"><p><a href=\"http:\/\/learnrussian.rt.com\/\">http:\/\/learnrussian.rt.com<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"539\"><p>Il corso \u00e8 destinato a principianti e ad apprendenti di livello intermedio<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"539\"><p><strong>Lessico<\/strong>, fonetica, grammatica, testi e dialoghi.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"539\"><p>Il corso, suddiviso in cento lezioni, \u00e8 composto da sette macrosezioni: <em>Lessons, Alphabet, Phonetics, Vocabulary, Tests, Grammar Tables, Topics. <\/em>In particolare, la sezione <em>Lessons <\/em>tratta svariati temi; ogni lezione contiene numerosi testi e offre la possibilit\u00e0 di svolgere varie attivit\u00e0, quali, ad esempio, ascoltare e completare i dialoghi, inserire la risposta corretta (domanda \u201cchiusa\u201d e scelta multipla), <em>cloze<\/em>, <em>cloze<\/em> facilitati ecc. La sezione <em>Alphabet<\/em>, corredata da file audio, presenta l\u2019alfabeto russo, oltre a una scheda sulla storia dell\u2019alfabeto cirillico. La sezione <em>Phonetics <\/em>si sofferma in dettaglio su vocali, consonanti, riduzione vocalica e, grazie a vari file audio, permette di esercitarsi nella pronuncia di consonanti palatalizzate e non palatalizzate e di far pratica con i diversi modelli intonativi tramite le frasi e i brevi dialoghi proposti. La sezione <em>Vocabulary<\/em>, ogni cinque unit\u00e0, riprende tutto il lessico incontrato nelle precedenti cinque unit\u00e0. Inoltre, ogni cinque lezioni, la sezione <em>Tests<\/em> propone un test per verificare l\u2019avvenuto apprendimento dei contenuti proposti. La sezione <em>Grammar Tables <\/em>permette di individuare facilmente l\u2019argomento di proprio interesse e l\u2019unit\u00e0 in cui questo \u00e8 stato trattato. La sezione <em>Topics<\/em>, infine, \u00e8 dedicata ad alcuni argomenti, quali i mezzi di trasporto, la casa e l\u2019abitazione, frasi idiomatiche ecc.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"539\"><p>Possibilit\u00e0 di visualizzare comodamente, in ogni schermata, la tastiera cirillica per scrivere, cliccando semplicemente sul pulsante <em>Cyrillic Keyboard<\/em>; ricchezza di contenuti e praticit\u00e0 d\u2019uso, interfaccia chiara e facilit\u00e0 di navigazione; dialoghi e testi presentano situazioni di vita quotidiana; le annotazioni di carattere metalinguistico, in lingua inglese, sono agili e intuitive; i file audio con l\u2019ascolto dei dialoghi e dei testi.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"539\"><p>Si tratta del corso di lingua russa proposto dal canale televisivo russo <em>Russia Today <\/em>(<em>RT<\/em>). \u00c8 anche possibile collegarsi, tramite il link riportato nella risorsa, a <em>RT News <\/em>per seguire le notizie di attualit\u00e0 e di cronaca sia in russo sia in altre lingue.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab7\" class=\"uc_ac_box elementor-repeater-item-1c5c0f7 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">UCLA Russian Language Program Grammar Interactive Exercises<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"539\"><p><strong><em>UCLA Russian Language Program Grammar Interactive Exercises<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"539\"><p><a href=\"http:\/\/www.russian.ucla.edu\/\">http:\/\/www.russian.ucla.edu<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"539\"><p>A1, A2, B1, B2<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"539\"><p><strong>Lessico<\/strong>, grammatica, sintassi, esercizi online, test di verifica a risposta multipla<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"539\"><p>Raccolta di esercizi suddivisi in quattro livelli, <em>Elementary <\/em>(A1)<em>, Intermediate <\/em>(A2)<em>, Intermediate Plus <\/em>(B1)<em>, Advanced <\/em>(B2). In dettaglio, per il livello A1 la risorsa propone un test lessico-grammaticale di cento domande; per il livello A2 esercizi sui casi e quattro test su verbi, lessico, grammatica e sull\u2019uso dei casi; per il livello B1 quattordici test su uso dei casi, sintassi, participi e gerundi, verbi di moto, aspetti del verbo ecc.; per il livello B2 esercizi su casi, preposizioni, verbi di moto, participi e gerundi, aspetto del verbo.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"539\"><p>Spiegazioni chiare ed essenziali, ricco apparato di esercizi, facilit\u00e0 d\u2019utilizzo della risorsa.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"539\"><p>Ente che ha realizzato la risorsa: University of California, Los Angeles (UCLA).<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab8\" class=\"uc_ac_box elementor-repeater-item-6a45932 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">LearningApps<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"539\"><p><strong><em>LearningApps<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"539\"><p><a href=\"https:\/\/learningapps.org\/\">https:\/\/learningapps.org\/<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"539\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"539\"><p><strong>Lessico<\/strong>, attivit\u00e0 ludiche per l\u2019acquisizione del lessico.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"539\"><p>La risorsa consente di realizzare attivit\u00e0 ludiche online e mette a disposizione svariati modelli per fare tali attivit\u00e0 relative al lessico (test a scelta multipla, abbinamenti parole-immagini, cruciverba, ecc.). Per creare esercizi di vocabolario, potete scegliere tra i seguenti modelli: esercizi di classificazione, test a scelta multipla, esercizi di abbinamento parola-immagine, esercizi di addizione, cruciverba, ecc.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"539\"><p>\u00c8 possibile sia realizzare i propri esercizi, sia utilizzare quelli caricati da altri utenti. \u00c8 altres\u00ec possibile effettuare ricerche sul sito per individuare temi di proprio interesse (ad esempio, \u201cNegozi\u201d, \u201cCitt\u00e0\u201d, ecc.). Trattasi di microattivit\u00e0 che possono essere facilmente integrate in qualsiasi corso di lingua o utilizzate in percorsi di autoapprendimento.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"539\"><p>L\u2019interfaccia \u00e8 disponibile in diverse lingue (inglese, francese, tedesco, spagnolo, italiano, russo).<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab9\" class=\"uc_ac_box elementor-repeater-item-9ff3fd0 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Wizer - Interactive Worksheets<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table width=\"669\"><tbody><tr><td width=\"135\"><p>Nome<\/p><\/td><td width=\"534\"><p><strong><em>Wizer - Interactive Worksheets<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"135\"><p>Indirizzo Internet<\/p><\/td><td width=\"534\"><p><a href=\"https:\/\/app.wizer.me\/\">https:\/\/app.wizer.me\/<\/a><\/p><\/td><\/tr><tr><td width=\"135\"><p>Livello<\/p><\/td><td width=\"534\"><p>A1, A2, B1<\/p><\/td><\/tr><tr><td width=\"135\"><p>Parole chiave<\/p><\/td><td width=\"534\"><p><strong>Lessico<\/strong>, fogli di lavoro interattivi, costruttore metodologico, lessico, attivit\u00e0 di apprendimento del lessico.<\/p><\/td><\/tr><tr><td width=\"135\"><p>Contenuti<\/p><\/td><td width=\"534\"><p>La risorsa consente di creare fogli di lavoro interattivi online, oltre a esercizi e attivit\u00e0 basati su modelli.<\/p><\/td><\/tr><tr><td width=\"135\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"534\"><p>Per lavorare sul lessico questa risorsa pu\u00f2 essere utilizzata per creare attivit\u00e0 di abbinamento, completamento, ecc., inserire immagini interattive; possibilit\u00e0 di caricare immagini, audio e video e link esterni ad altre risorse. Possibilit\u00e0 di registrare la voce e lavorare sulla pronuncia.<\/p><p>Interfaccia solo in inglese.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab10\" class=\"uc_ac_box elementor-repeater-item-7644828 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Thinglink<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table width=\"669\"><tbody><tr><td width=\"134\"><p>Nome<\/p><\/td><td width=\"535\"><p><strong><em>Thinglink<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"134\"><p>Indirizzo Internet<\/p><\/td><td width=\"535\"><p><a href=\"https:\/\/www.thinglink.com\/\">https:\/\/www.thinglink.com\/<\/a><\/p><\/td><\/tr><tr><td width=\"134\"><p>Livello<\/p><\/td><td width=\"535\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"134\"><p>Parole chiave<\/p><\/td><td width=\"535\"><p><strong>Lessico<\/strong>, immagini interattive.<\/p><\/td><\/tr><tr><td width=\"134\"><p>Contenuti<\/p><\/td><td width=\"535\"><p>Risorsa per la creazione di immagini interattive. Consente di caricare un\u2019immagine (disegno, foto) e di \u201canimarla\u201d, aggiungendo dei tag speciali, ossia dei collegamenti che, se cliccati, permettono di accedere a materiali aggiuntivi (testi, altre immagini, audio o video caricati).<\/p><\/td><\/tr><tr><td width=\"134\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"535\"><p>Per lavorare sul lessico \u00e8 possibile usare questa risorsa per creare immagini interattive che includono testi e alle quali pu\u00f2 essere aggiunta una registrazione vocale.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab11\" class=\"uc_ac_box elementor-repeater-item-7fbe296 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Coggle <\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table width=\"669\"><tbody><tr><td width=\"135\"><p>Nome<\/p><\/td><td width=\"534\"><p><strong><em>Coggle <\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"135\"><p>Indirizzo Internet<\/p><\/td><td width=\"534\"><p><a href=\"https:\/\/coggle.it\/\">https:\/\/coggle.it\/<\/a><\/p><\/td><\/tr><tr><td width=\"135\"><p>Livello<\/p><\/td><td width=\"534\"><p>A1, A2, B1<\/p><\/td><\/tr><tr><td width=\"135\"><p>Parole chiave<\/p><\/td><td width=\"534\"><p><strong>Lessico<\/strong>, supporto visivo.<\/p><\/td><\/tr><tr><td width=\"135\"><p>Contenuti<\/p><\/td><td width=\"534\"><p>Questa risorsa pu\u00f2 essere utilizzata per visualizzare e sistematizzare il lessico gi\u00e0 noto e altres\u00ec per ampliare il bagaglio lessicale degli studenti. Le mappe mentali possono essere utilizzate per visualizzare gruppi tematici. Al centro viene collocato un concetto generico e intorno a questo vengono disposti esempi concreti relativi allo stesso. Per un\u2019efficace acquisizione del lessico, si possono creare combinazioni di parole e frasi con le parole rappresentate in questo modo. La mappa mentale pu\u00f2 essere elaborata dagli studenti, individualmente o in mini-gruppo con altri studenti online.<\/p><\/td><\/tr><tr><td width=\"135\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"534\"><p>Possibilit\u00e0 di aggiungere ad ogni ramo della mappa mentale un\u2019etichetta di testo, caricare un\u2019immagine o aggiungere un link a una risorsa esterna. Queste funzioni permettono di strutturare le informazioni e, di conseguenza, renderle pi\u00f9 accessibili e fruibili visivamente. \u00c8 anche possibile scaricare le mappe in formato PDF.<\/p><\/td><\/tr><tr><td width=\"135\"><p>Annotazioni<\/p><\/td><td width=\"534\"><p>Per approfondimenti relativi all\u2019uso delle mappe mentali, si rimanda, in particolare, a Buzan, Buzan (2013).<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab12\" class=\"uc_ac_box elementor-repeater-item-90e7282 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Word It Out<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table width=\"669\"><tbody><tr><td width=\"134\"><p>Nome<\/p><\/td><td width=\"534\"><p><strong><em>Word It Out<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"134\"><p>Indirizzo Internet<\/p><\/td><td width=\"534\"><p><a href=\"https:\/\/worditout.com\/\">https:\/\/worditout.com\/<\/a><\/p><\/td><\/tr><tr><td width=\"134\"><p>Livello<\/p><\/td><td width=\"534\"><p>A1, A2<\/p><\/td><\/tr><tr><td width=\"134\"><p>Parole chiave<\/p><\/td><td width=\"534\"><p><strong>Lessico<\/strong>, nuvole di parole.<\/p><\/td><\/tr><tr><td width=\"134\"><p>Contenuti<\/p><\/td><td width=\"534\"><p>Questa risorsa consente di presentare visivamente elenchi di parole o piccoli testi sotto forma di \u201cnuvola\u201d. \u00c8 possibile proporre diversi tipi di lavoro sul lessico presentato sotto forma di \u201cnuvola\u201d, ad esempio, individuare nella \u201cnuvola\u201d le parole appartenenti a un medesimo gruppo tematico, trovare coppie (sinonimi, contrari), trovare la parola superflua\/estranea nel gruppo, creare frasi con parole nuove, ecc.<\/p><\/td><\/tr><tr><td width=\"134\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"534\"><p>Questa risorsa, di facile utilizzo, non richiede alcuna registrazione.<\/p><\/td><\/tr><tr><td width=\"134\"><p>Annotazioni<\/p><\/td><td width=\"534\"><p>L\u2019interfaccia della risorsa \u00e8 in inglese.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab13\" class=\"uc_ac_box elementor-repeater-item-9841983 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Quizlet<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table width=\"669\"><tbody><tr><td width=\"135\"><p>Nome<\/p><\/td><td width=\"534\"><p><strong><em>Quizlet<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"135\"><p>Indirizzo Internet<\/p><\/td><td width=\"534\"><p><a href=\"https:\/\/quizlet.com\/\">https:\/\/quizlet.com\/<\/a><\/p><\/td><\/tr><tr><td width=\"135\"><p>Livello<\/p><\/td><td width=\"534\"><p>A1, A2, B1<\/p><\/td><\/tr><tr><td width=\"135\"><p>Parole chiave<\/p><\/td><td width=\"534\"><p><strong>Lessico<\/strong>, <em>flashcards<\/em>, schede digitali, supporti visivi, acquisizione del lessico.<\/p><\/td><\/tr><tr><td width=\"135\"><p>Contenuti<\/p><\/td><td width=\"534\"><p>La risorsa consente di realizzare schede digitali per memorizzare e ripetere i vocaboli.<\/p><\/td><\/tr><tr><td width=\"135\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"534\"><p>Possibilit\u00e0 di realizzare diversi tipi di schede per l\u2019apprendimento di nuove parole: vocabolo e immagine, vocabolo e suo traducente, termine e sua definizione nella lingua target, esempi d\u2019uso.<\/p><p>Per evitare che gli studenti si limitino semplicemente a scorrere in modo automatico le schede con il lessico, possono essere proposte varie attivit\u00e0, quali, ad esempio, comporre una frase a partire da un dato vocabolo della scheda, formulare una domanda che includa il vocabolo in questione, costruire un dialogo usando diverse schede, ecc.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab14\" class=\"uc_ac_box elementor-repeater-item-31d0823 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Words Tool <\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table width=\"669\"><tbody><tr><td width=\"134\"><p>Nome<\/p><\/td><td width=\"534\"><p><strong><em>Words Tool <\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"134\"><p>Indirizzo Internet<\/p><\/td><td width=\"534\"><p><a href=\"https:\/\/wordstool.com\/\">https:\/\/wordstool.com\/<\/a><\/p><\/td><\/tr><tr><td width=\"134\"><p>Livello<\/p><\/td><td width=\"534\"><p>A1, A2, B1<\/p><\/td><\/tr><tr><td width=\"134\"><p>Parole chiave<\/p><\/td><td width=\"534\"><p><strong>Lessico<\/strong>, schede e tabelle digitali, supporti visivi, acquisizione del lessico.<\/p><\/td><\/tr><tr><td width=\"134\"><p>Contenuti<\/p><\/td><td width=\"534\"><p>Piattaforma appositamente realizzata per studiare i vocaboli e realizzare attivit\u00e0 relative al lessico. Consente di fissare e organizzare il materiale lessicale. Possibilit\u00e0 di realizzare schede digitali che includono le seguenti informazioni: vocabolo, traducente, definizione, pronuncia, raffigurazione, sinonimi e contrari, esempi d\u2019uso.<\/p><\/td><\/tr><tr><td width=\"134\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"534\"><p>Questa risorsa consente di creare la propria banca di vocaboli a partire dalle proprie schede. \u00c8 anche possibile utilizzare <em>flashcard<\/em> gi\u00e0 pronte ed esercizi creati da altri utenti. Vengono proposte svariate attivit\u00e0, quali dettati, cruciverba, anagrammi, attivit\u00e0 di completamento, abbinamento e a scelta multipla. \u00c8 altres\u00ec possibile realizzare proprie attivit\u00e0 ed esercizi a partire da mappe di parole gi\u00e0 pronte, inserendole nell\u2019ordine giusto. Inoltre, \u00e8 possibile salvare i propri esercizi come modelli e poi utilizzarli per crearne di nuovi, utilizzando un lessico differente.<\/p><\/td><\/tr><tr><td width=\"134\"><p>Annotazioni<\/p><\/td><td width=\"534\"><p>L\u2019interfaccia della risorsa \u00e8 in inglese.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab15\" class=\"uc_ac_box elementor-repeater-item-f61cfdf \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">SKELL - Sketch Engine for language learning<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"> <\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"140\"><p>Nome<\/p><\/td><td width=\"529\"><p><strong><em>SKELL - Sketch Engine for language learning<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"140\"><p>Indirizzo Internet<\/p><\/td><td width=\"529\"><p><a href=\"https:\/\/skell.sketchengine.eu\/#home?lang=ru\">https:\/\/skell.sketchengine.eu\/#home?lang=ru<\/a><\/p><\/td><\/tr><tr><td width=\"140\"><p>Livello<\/p><\/td><td width=\"529\"><p>da A2 a C2<\/p><\/td><\/tr><tr><td width=\"140\"><p>Parole chiave<\/p><\/td><td width=\"529\"><p><strong>Lessico<\/strong>, strumento online basato su <em>corpora<\/em>, combinabilit\u00e0 delle parole, associazione, uso delle parole.<\/p><\/td><\/tr><tr><td width=\"140\"><p>Contenuti<\/p><\/td><td width=\"529\"><p>SKELL \u00e8 uno strumento basato su <em>corpora<\/em> per studiare la combinabilit\u00e0 delle parole nel contesto. Questa risorsa ha tre funzioni: <em>Examples<\/em> (frasi brevi e chiare che rappresentano l\u2019uso delle parole nel contesto), <em>Word sketch<\/em> (esempi di comuni combinazioni di parole), <em>Similar words <\/em>(esempi di parole semanticamente simili, sinonimi, contrari).<\/p><\/td><\/tr><tr><td width=\"140\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"529\"><p>Trattasi di un motore di ricerca che non richiede registrazione per l\u2019utilizzo. La risorsa pu\u00f2 essere utilizzata nelle seguenti lingue: inglese, tedesco, italiano, russo, ceco, estone e russo.<\/p><\/td><\/tr><tr><td width=\"140\"><p>Annotazioni<\/p><\/td><td width=\"529\"><p>Questa risorsa pu\u00f2 essere utilizzata dagli insegnanti per preparare i propri materiali didattici per attivit\u00e0 relative al lessico, ad esempio, cloze-test, ricerca di esempi di combinazioni di parole, costruzione di frasi basate su parole semanticamente simili, ecc.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab16\" class=\"uc_ac_box elementor-repeater-item-bad2a9f \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">CoCoCo Collocations Colligations Corpora<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"539\"><p><strong><em>CoCoCo Collocations Colligations Corpora<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"539\"><p><a href=\"https:\/\/cococo.cosyco.ru\">https:\/\/cococo.cosyco.ru<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"539\"><p>Tutti i livelli<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"539\"><p><strong>Lessico<\/strong>, collocazioni, idiomi, combinabilit\u00e0 di parole<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"539\"><p>Motore di ricerca per la consultazione di combinazioni di parole; il <em>database<\/em> di circa 150 milioni di parole e relative combinazioni pi\u00f9 stabili e frequenti \u00e8 articolato in tre diversi tipi di <em>corpora<\/em> sui quali si basa la ricerca; tutorial sull\u2019uso della risorsa; articoli e materiale di approfondimento.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"539\"><p>Motore di ricerca per combinazioni di parole, gratuito e di facile utilizzo, che permette di migliorare la padronanza della lingua <em>target<\/em>, evitando all\u2019apprendente errori, dovuti molto spesso ai meccanismi di interferenza linguistica della L1; possibilit\u00e0 di effettuare ricerche rapide e precise; anche a livello di competenza linguistica non particolarmente avanzata, pu\u00f2 essere un utile stimolo al corretto uso delle collocazioni e d\u00e0 un\u2019idea della frequenza d\u2019uso di combinazioni di parole; possibilit\u00e0 di impostare filtri relativi alle parti del discorso da ricercare in modo da limitare e finalizzare i risultati della ricerca; permette di effettuare ricerche avanzate e di esportare i dati direttamente in formato Excel.<\/p><p>Due sole sono le lingue dell\u2019interfaccia, l\u2019inglese e il russo, di conseguenze, l\u2019accesso e l\u2019impiego della risorsa pu\u00f2 risultare difficoltoso per i principianti e, in generale, per coloro che non possiedono buone competenze in nessuna delle due lingue; la risorsa permette solo di ricercare le collocazioni, ossia di essere impiegata come mero strumento di consultazione, non essendo prevista la possibilit\u00e0 di fare esercizi.<\/p><p>Interfaccia intuitive e di facile comprensione, grafica semplice e gradevole.<\/p><p>Buon livello di interattivit\u00e0 della risorsa.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"539\"><p>Valido strumento online per l\u2019apprendimento di collocazioni e forme idiomatiche.<\/p><p>La risorsa \u00e8 sviluppata da un gruppo di ricerca dell\u2019Universit\u00e0 di Helsinki, sotto la supervisione del Prof. M. Kopotev. Il progetto si basa su approcci <em>corpus based <\/em>e su metodi statistici per analizzare le combinazioni di parole. La banca dati \u00e8 costituita da circa 150 milioni di parole e loro combinazioni pi\u00f9 stabili e frequenti. L\u2019interfaccia della risorsa \u00e8 sia in lingua russa sia in lingua inglese.<\/p><p>La risorsa pu\u00f2 essere facilmente impiegata in caso di apprendimento individuale, di gruppo e personalizzato. Possibilit\u00e0 d\u2019uso di questo motore di ricerca per analizzare la combinabilit\u00e0 delle parole in prospettiva contrastiva.<\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n  <\/div>\n<\/div>\n\t\t\t<!-- end Content Accordion -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17cdb87 elementor-widget elementor-widget-image\" data-id=\"17cdb87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian2-1024x683.png\" class=\"attachment-large size-large wp-image-70\" alt=\"\" srcset=\"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian2-1024x683.png 1024w, https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian2-300x200.png 300w, https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian2-768x512.png 768w, https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian2.png 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n\n<\/div>\n<div class=\"elementor-element elementor-element-1a5ca35 e-con e-atomic-element e-flexbox-base e-89a987f \" data-id=\"1a5ca35\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"1a5ca35\">\n    \t\t<div class=\"elementor-element elementor-element-e899665 elementor-widget elementor-widget-text-editor\" data-id=\"e899665\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Alcuni strumenti online di rapida consultazione<\/strong><\/h3><p>Data l\u2019estrema importanza della lingua viva, di seguito, in questa sezione segnaliamo una lista di siti di ragguardevole interesse per esercitare, grazie alla presenza di <em>podcast<\/em>, la comprensione orale (<em>audirovanie<\/em>). Trattasi di risorse particolarmente adatte ad apprendenti di livello avanzato in quanto offrono numerosi esempi di stile colloquiale, unit\u00e0 fraseologiche e <em>slang<\/em> giovanile. Inoltre, indichiamo sinteticamente alcuni dizionari ed enciclopedie online, oltre ad alcuni strumenti di facile e veloce utilizzo che, in caso di dubbi, consentono di compiere varie operazioni, quali verificare e consultare l\u2019ortografia e la declinazione dei numerali, la declinazione di un sostantivo, la coniugazione di un verbo, la formazione e la declinazione di antroponimi (nomi, patronimici e cognomi russi) che, spesso, nascondono insidie per gli studenti meno esperti. Infine, per i docenti segnaliamo <em>Wooclap, <\/em>una risorsa di facile utilizzo per realizzare esercizi interattivi da impiegare in aula anche con gruppi particolarmente numerosi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-b8e7002 e-con e-atomic-element e-flexbox-base e-42489b1 \" data-id=\"b8e7002\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"b8e7002\">\n    <div class=\"elementor-element elementor-element-bc8c148 e-con e-atomic-element e-flexbox-base e-f491341 \" data-id=\"bc8c148\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"bc8c148\">\n    \t\t<div class=\"elementor-element elementor-element-a38fe98 elementor-widget elementor-widget-text-editor\" data-id=\"a38fe98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>Risorse per la comprensione orale<br \/><\/b><\/h3><p><span style=\"font-style: inherit; font-weight: inherit;\">Per esercitare la <\/span><strong style=\"font-style: inherit;\">comprensione orale<\/strong><span style=\"font-style: inherit; font-weight: inherit;\">, tra le varie risorse disponibili, in particolare segnaliamo:<\/span><\/p><p>Indirizzo Internet<a href=\"http:\/\/www.bbcrussian.com\">www.bbcrussian.com<\/a>Nome<strong><em>Moskovskie novosti<\/em><\/strong><\/p><table style=\"width: 100%; height: 1176px;\"><tbody><tr style=\"height: 59px;\"><td style=\"height: 59px; width: 20.9983%;\" width=\"100\">Nome<\/td><td style=\"height: 59px; width: 78.8296%;\" width=\"200\"><strong><em>BBC Russkaja slu<\/em><\/strong><strong><em>\u017e<\/em><\/strong><strong><em>ba<\/em><\/strong><\/td><\/tr><tr style=\"height: 26px;\"><td style=\"height: 26px; width: 20.9983%;\" width=\"124\">Web<\/td><td style=\"height: 26px; width: 78.8296%;\" width=\"494\"><a href=\"http:\/\/www.mn.ru\">www.mn.ru<\/a><\/td><\/tr><tr style=\"height: 59px;\"><td style=\"height: 59px; width: 20.9983%;\" width=\"124\">Nome<\/td><td style=\"height: 59px; width: 78.8296%;\" width=\"494\"><strong><em>NEWSru.com<\/em><\/strong><\/td><\/tr><tr style=\"height: 60px;\"><td style=\"height: 60px; width: 20.9983%;\" width=\"124\">Web<\/td><td style=\"height: 60px; width: 78.8296%;\" width=\"494\"><a href=\"http:\/\/www.newsru.com\">www.newsru.com<\/a><\/td><\/tr><tr style=\"height: 59px;\"><td style=\"height: 59px; width: 20.9983%;\" width=\"124\">Nome<\/td><td style=\"height: 59px; width: 78.8296%;\" width=\"494\"><strong><em>Pravda.Ru<\/em><\/strong><\/td><\/tr><tr style=\"height: 51px;\"><td style=\"height: 51px; width: 20.9983%;\" width=\"124\">Web<\/td><td style=\"height: 51px; width: 78.8296%;\" width=\"494\"><a href=\"http:\/\/www.pravda.ru\">www.pravda.ru<\/a><\/td><\/tr><tr style=\"height: 59px;\"><td style=\"height: 59px; width: 20.9983%;\" width=\"124\">Nome<\/td><td style=\"height: 59px; width: 78.8296%;\" width=\"494\"><strong><em>Rossijskie Vesti<\/em><\/strong><\/td><\/tr><tr style=\"height: 58px;\"><td style=\"height: 58px; width: 20.9983%;\" width=\"124\">Web<\/td><td style=\"height: 58px; width: 78.8296%;\" width=\"494\"><a href=\"http:\/\/rosvesty.ru\">http:\/\/rosvesty.ru<\/a><\/td><\/tr><tr style=\"height: 59px;\"><td style=\"height: 59px; width: 20.9983%;\" width=\"124\">Nome<\/td><td style=\"height: 59px; width: 78.8296%;\" width=\"494\"><strong><em>Utro.ru<\/em><\/strong><\/td><\/tr><tr style=\"height: 55px;\"><td style=\"height: 55px; width: 20.9983%;\" width=\"124\">Web<\/td><td style=\"height: 55px; width: 78.8296%;\" width=\"494\"><a href=\"http:\/\/www.utro.ru\">www.utro.ru<\/a><\/td><\/tr><tr style=\"height: 59px;\"><td style=\"height: 59px; width: 20.9983%;\" width=\"124\">Nome<\/td><td style=\"height: 59px; width: 78.8296%;\" width=\"494\"><strong><em>Vesti.ru<\/em><\/strong><\/td><\/tr><tr style=\"height: 54px;\"><td style=\"height: 54px; width: 20.9983%;\" width=\"124\">Web<\/td><td style=\"height: 54px; width: 78.8296%;\" width=\"494\"><a href=\"http:\/\/www.vesti.ru\">www.vesti.ru<\/a><\/td><\/tr><tr style=\"height: 59px;\"><td style=\"height: 59px; width: 20.9983%;\" width=\"124\">Nome<\/td><td style=\"height: 59px; width: 78.8296%;\" width=\"494\"><strong><em>Echo Moskvy<\/em><\/strong><\/td><\/tr><tr style=\"height: 53px;\"><td style=\"height: 53px; width: 20.9983%;\" width=\"124\">Web<\/td><td style=\"height: 53px; width: 78.8296%;\" width=\"494\"><a href=\"http:\/\/www.echo.msk.ru\">www.echo.msk.ru<\/a><\/td><\/tr><tr style=\"height: 59px;\"><td style=\"height: 59px; width: 20.9983%;\" width=\"124\">Nome<\/td><td style=\"height: 59px; width: 78.8296%;\" width=\"494\"><strong><em>Radio Svoboda<\/em><\/strong><\/td><\/tr><tr style=\"height: 46px;\"><td style=\"height: 46px; width: 20.9983%;\" width=\"124\">Web<\/td><td style=\"height: 46px; width: 78.8296%;\" width=\"494\"><a href=\"http:\/\/www.svoboda.org\">www.svoboda.org<\/a><\/td><\/tr><tr style=\"height: 93px;\"><td style=\"height: 93px; width: 20.9983%;\" width=\"124\">Nome<\/td><td style=\"height: 93px; width: 78.8296%;\" width=\"494\"><strong><em>Short Audio &amp; Video Lessons for Fast and Easy Learning<\/em><\/strong><\/td><\/tr><tr style=\"height: 53px;\"><td style=\"height: 53px; width: 20.9983%;\" width=\"124\">Web<\/td><td style=\"height: 53px; width: 78.8296%;\" width=\"494\"><a href=\"http:\/\/www.russianpod101.com\">www.russianpod101.com<\/a><\/td><\/tr><tr style=\"height: 93px;\"><td style=\"height: 93px; width: 20.9983%;\" width=\"124\">Nome<\/td><td style=\"height: 93px; width: 78.8296%;\" width=\"494\"><strong><em>Very Much Russian. Learn Russian as Russians speak it!<\/em><\/strong><\/td><\/tr><tr style=\"height: 62px;\"><td style=\"height: 62px; width: 20.9983%;\" width=\"124\">Web<\/td><td style=\"height: 62px; width: 78.8296%;\" width=\"494\"><a href=\"http:\/\/www.ochenporusski.com\">www.ochenporusski.com<\/a><\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-618753c e-con e-atomic-element e-flexbox-base e-a7818b8 \" data-id=\"618753c\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"618753c\">\n    \t\t<div class=\"elementor-element elementor-element-f319f50 elementor-widget elementor-widget-text-editor\" data-id=\"f319f50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Dizionari ed enciclopedie online<\/strong><\/h3><p>Gli strumenti di seguito indicati possono risultare particolarmente utili per compiere varie operazioni<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ecf3fc elementor-widget elementor-widget-ucaddon_content_accordion\" data-id=\"9ecf3fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_content_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- start Content Accordion -->\n\n\t\t\t<style type=\"text\/css\">\/* widget: Content Accordion *\/\n\n\n\n#uc_content_accordion_elementor_9ecf3fc *{\n  box-sizing: border-box;\n}\n\n#uc_content_accordion_elementor_9ecf3fc .ue_heading_title{\n  margin:0;\n  flex-grow:1;\n  display:flex;\n  flex-direction:row;\n}\n\n#uc_content_accordion_elementor_9ecf3fc .uc_container .uc-heading{\n\tdisplay:flex;\n    align-items:center;\n\toverflow:hidden;\n\tcursor:pointer;  \n}\n\n#uc_content_accordion_elementor_9ecf3fc .uc_container .uc_content{\n    display:none;\n}\n\n#uc_content_accordion_elementor_9ecf3fc .uc_container .uc-heading span.ue_accordion_icon{\n\tdisplay:flex;\n    align-items:center;\n   \tjustify-content:center;\n    flex-grow:0;\n    flex-shrink:0;\n}\n\n#uc_content_accordion_elementor_9ecf3fc .uc_ac_box.uc-item-active span.uc_dactive{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_9ecf3fc .uc_ac_box:not(.uc-item-active) span.uc_active{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_9ecf3fc span.ue_accordion_icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_content_accordion_elementor_9ecf3fc .uc_container .uc_btn {\n    text-align: center;\n    display: inline-block;\n    text-decoration: none;\n    transition: ease-in-out all 0.25s;\n}\n\n#uc_content_accordion_elementor_9ecf3fc .ue-item-image img{\n  width:100%;\n  display:block;\n  object-fit:cover;\n}\n\n<\/style>\n\n\t\t\t<div class=\"uc_material_accordion  \"  id=\"uc_content_accordion_elementor_9ecf3fc\"  data-name=\"\" data-scroll=\"off\" data-offset=\"0\" data-closeothers=\"true\" data-set-hash=\"false\" data-transition-duration=\"400\" >\n  <div class=\"uc_container uc-items-wrapper\">\n    \n\n\n\n\n<div id=\"#ue-tab1\" class=\"uc_ac_box elementor-repeater-item-0a96546 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Gramota.Ru \u2013 Russkij jazyk dlja vsech<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>Gramota.Ru \u2013 Russkij jazyk dlja vsech<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"http:\/\/gramota.ru\">http:\/\/gramota.ru<\/a>; <a href=\"http:\/\/gramota.ru\/slovari\">http:\/\/gramota.ru\/slovari<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>Da B1 a C2<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p>Lessico, dizionari online, letteratura classica e contemporanea, accesso a riviste in lingua russa, forum di discussione con esperti e linguisti, manuali online di lingua russa, giochi interattivi, rompicapo e quiz, proverbi, modi di dire e scioglilingua.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>Il portale dedicato alla lingua russa \u00e8 organizzato nelle seguenti sei macrosezioni: <em>Slovari<\/em>,<em> Biblioteka<\/em>,<em> Spravka<\/em>,<em> Klass<\/em>,<em> Lenta <\/em>e <em>Igra<\/em>. In particolare, segnaliamo che nella sezione <em>Slovari<\/em>, tra i vari dizionari disponibili online (anche in formato audio), \u00e8 possibile consultare anche <em>Slovar\u2019 russkogo argo <\/em>e <em>Slovar\u2019 pravoslavnoj cerkovnoj leksiki.<\/em> Nella sezione <em>Biblioteka <\/em>\u00e8 possibile leggere i testi della letteratura anticorussa, le opere dei pi\u00f9 importanti autori russi (XVIII, XIX, XX secc.) e accedere, tramite la sottosezione <em>\u017durnaly <\/em>a riviste online, quali <em>Nauka i \u017e<\/em><em>izn\u2019<\/em>,<em> Russkij jazyk v <\/em><em>\u0161kole<\/em>,<em> Russkij jazyk za rube<\/em><em>\u017e<\/em><em>om<\/em>,<em> Russkaja re<\/em><em>\u010d<\/em><em>\u2019<\/em>,<em> Mir russkogo slova<\/em>. Nella sezione <em>Klass <\/em>\u00e8 possibile accedere a diversi manuali di lingua russa tramite la sottosezione <em>U<\/em><em>\u010d<\/em><em>ebniki<\/em> ed \u00e8 possibile esercitarsi con dettati interattivi tramite la sottosezione <em>Repetitor onlajn<\/em>. Nella sezione <em>Lenta<\/em>, invece, \u00e8 possibile reperire informazioni, notizie e comunicazioni varie su eventi, conferenze, seminari relativi alla lingua russa. Nella sezione <em>Igra <\/em>si segnalano, in particolare, rompicapo e numerosi indovinelli con le relative soluzioni.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>Oltre a consentire agli utenti di comprendere il significato e i contesti d\u2019uso di un vocabolo, la risorsa permette di controllare l\u2019ortografia, l\u2019accento e di individuare sinonimi e contrari. La sottosezione <em>Russkij ustnyj<\/em>, progetto dell\u2019emittente radiofonica \u00ab<em>Golos Rossii\u00bb<\/em>; sottosezione <em>Govori pravil\u2019no<\/em> propone i file audio della trasmissione radiofonica \u00ab<em>Slovar\u2019 udarenij\u00bb<\/em> del canale moscovita \u00ab<em>Radio7\u00bb<\/em>; numerosi collegamenti a siti utili.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>Il portale in lingua russa \u00e8 attivo grazie al sostegno finanziario dell\u2019Agenzia federale per la stampa e comunicazioni di massa (<em>Rospe<\/em><em>\u010d<\/em><em>at\u2019<\/em>); il forum tematico con le risposte degli esperti, nella sezione <em>Spravki<\/em>, \u00e8 un servizio congiunto, offerto dall\u2019Istituto di lingua russa \u00abV.V. Vinogradov\u00bb dell\u2019Accademia russa e dal portale <em>Gramota.Ru<\/em>.<\/p><p>Si tratta di un portale molto vario in cui studenti di livello intermedio o avanzato possono trovare diversi strumenti, quali dizionari (monolingue, ortografico, prosodico, dei sinonimi e dei contrari), oltre a podcast di trasmissioni radiofoniche.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab2\" class=\"uc_ac_box elementor-repeater-item-e18d9c9 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Wikizionari<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>Wikizionario<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"https:\/\/it.wiktionary.org\">https:\/\/it.wiktionary.org<\/a> (versione italiana)<\/p><p><a href=\"https:\/\/ru.wiktionary.org\">https:\/\/ru.wiktionary.org<\/a> (versione russa)<\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>Tutti i livelli<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p>Dizionario online<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>Sono presenti tabelle relative alla flessione nominale e verbale.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>Risorsa gratuita con contenuti liberi, collaborativi, multilingue.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>Oltre a verificare significati, contesti d\u2019uso, sinonimi e contrari, la risorsa pu\u00f2 essere impiegata per consultare l\u2019ortografia e l\u2019accento di un vocabolo, la declinazione di un sostantivo e la coniugazione di un verbo.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n  <\/div>\n<\/div>\n\t\t\t<!-- end Content Accordion -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4da3592 elementor-widget elementor-widget-spacer\" data-id=\"4da3592\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9fb319 elementor-widget elementor-widget-text-editor\" data-id=\"a9fb319\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Dizionari ed enciclopedie online<\/strong><\/h3><p>Gli strumenti di seguito indicati possono risultare particolarmente utili per compiere varie operazioni<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9225b0a elementor-widget elementor-widget-ucaddon_content_accordion\" data-id=\"9225b0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_content_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- start Content Accordion -->\n\n\t\t\t<style type=\"text\/css\">\/* widget: Content Accordion *\/\n\n\n\n#uc_content_accordion_elementor_9225b0a *{\n  box-sizing: border-box;\n}\n\n#uc_content_accordion_elementor_9225b0a .ue_heading_title{\n  margin:0;\n  flex-grow:1;\n  display:flex;\n  flex-direction:row;\n}\n\n#uc_content_accordion_elementor_9225b0a .uc_container .uc-heading{\n\tdisplay:flex;\n    align-items:center;\n\toverflow:hidden;\n\tcursor:pointer;  \n}\n\n#uc_content_accordion_elementor_9225b0a .uc_container .uc_content{\n    display:none;\n}\n\n#uc_content_accordion_elementor_9225b0a .uc_container .uc-heading span.ue_accordion_icon{\n\tdisplay:flex;\n    align-items:center;\n   \tjustify-content:center;\n    flex-grow:0;\n    flex-shrink:0;\n}\n\n#uc_content_accordion_elementor_9225b0a .uc_ac_box.uc-item-active span.uc_dactive{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_9225b0a .uc_ac_box:not(.uc-item-active) span.uc_active{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_9225b0a span.ue_accordion_icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_content_accordion_elementor_9225b0a .uc_container .uc_btn {\n    text-align: center;\n    display: inline-block;\n    text-decoration: none;\n    transition: ease-in-out all 0.25s;\n}\n\n#uc_content_accordion_elementor_9225b0a .ue-item-image img{\n  width:100%;\n  display:block;\n  object-fit:cover;\n}\n\n<\/style>\n\n\t\t\t<div class=\"uc_material_accordion  \"  id=\"uc_content_accordion_elementor_9225b0a\"  data-name=\"\" data-scroll=\"off\" data-offset=\"0\" data-closeothers=\"true\" data-set-hash=\"false\" data-transition-duration=\"400\" >\n  <div class=\"uc_container uc-items-wrapper\">\n    \n\n\n\n\n<div id=\"#ue-tab1\" class=\"uc_ac_box elementor-repeater-item-0a96546 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Surname Online<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"126\"><p>Nome<\/p><\/td><td width=\"524\"><p><strong><em>Surname Online<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"126\"><p>Indirizzo Internet<\/p><\/td><td width=\"524\"><p><a href=\"https:\/\/surnameonline.ru\">https:\/\/surnameonline.ru<\/a><\/p><\/td><\/tr><tr><td width=\"126\"><p>Parole chiave<\/p><\/td><td width=\"524\"><p>Nomi, cognomi e patronimici russi<\/p><\/td><\/tr><tr><td width=\"126\"><p>Contenuti<\/p><\/td><td width=\"524\"><p>Declinazione di nomi, patronimici e cognomi russi in tutti i casi, al singolare e al plurale.<\/p><\/td><\/tr><tr><td width=\"126\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"524\"><p>Di facilissimo utilizzo, una volta compilati gli appositi campi con l\u2019indicazione del nome, del patronimico e del cognome (\u0424\u0418\u041e) d\u2019interesse, la risorsa restituisce immediatamente i risultati della ricerca, ossia la declinazione degli antroponimi nei vari casi, al singolare e al plurale.<\/p><\/td><\/tr><tr><td width=\"126\"><p>Annotazioni<\/p><\/td><td width=\"524\"><p>In caso di dubbi relativi alla declinazione di nomi, patronimici e cognomi russi questa risorsa \u00e8 un utile strumento.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab2\" class=\"uc_ac_box elementor-repeater-item-48f82f1 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Morfologija<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>Morfologija<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"http:\/\/morfologija.ru\">http:\/\/morfologija.ru<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>Tutti i livelli<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p>Dizionario morfologico della lingua russa.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>Il dizionario morfologico contiene pi\u00f9 di 170 mila parole e pi\u00f9 di 5 milioni di forme verbali.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>Una volta compilato l\u2019apposito campo con la voce di proprio interesse e premuto il pulsante (\u201c\u0418\u0441\u043a\u0430\u0442\u044c\u201d), la risorsa restituisce immediatamente tabelle di facile e rapida consultazione con la declinazione del sostantivo o la coniugazione del verbo cercato.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>L\u2019interfaccia del sito \u00e8 in lingua russa. Nel dizionario di possono altres\u00ec effettuare ricerche senza inserire la forma completa della parola, bens\u00ec digitando il simbolo asterisco (*) al posto di alcune lettere. Questa modalit\u00e0 consente di effettuare ricerche contemporaneamente su pi\u00f9 parole.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab3\" class=\"uc_ac_box elementor-repeater-item-20cb2c7 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Mephist<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>Mephist<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"http:\/\/live.mephist.ru\/show\/number-naming\">http:\/\/live.mephist.ru\/show\/number-naming<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>Tutti i livelli<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p>Numerali<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>Declinazione dei numerali cardinali nei vari casi.<\/p><p>\u00a0<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>La risorsa fornisce immediatamente la forma del numerale in lettere nel caso richiesto.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>Una volta digitato il numero di proprio interesse in cifre e cliccato sul pulsante del relativo caso, viene visualizzata la forma del numerale cardinale nel caso richiesto.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab4\" class=\"uc_ac_box elementor-repeater-item-5d42642 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Online.orfo<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong>Online.orfo<\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"http:\/\/online.orfo.ru\">http:\/\/online.orfo.ru<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>Tutti i livelli<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p>Norme di ortografia russa.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>La risorsa permette di chiarire i dubbi relativi all\u2019ortografia russa. Ad esempio, i casi in cui viene utilizzata la particella negativa \u043d\u0438 e \u043d\u0435; uso del trattino o meno nelle parole composte ecc.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>Per utilizzare questa risorsa \u00e8 necessario effettuare la registrazione. La risorsa \u00e8 molto utile per ripassare le norme dell\u2019ortografia russa o in caso di dubbi sulla corretta grafia di una parola.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>Una volta inserito nell\u2019apposito campo un testo in russo (o in un\u2019altra lingua), la risorsa effettuer\u00e0 un controllo ortografico, sottolineando in rosso le parole non corrette.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab5\" class=\"uc_ac_box elementor-repeater-item-8fadda6 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">RussianGram.com<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>RussianGram.com<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"http:\/\/russiangram.com\">http:\/\/russiangram.com<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>Tutti i livelli<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p>Accento grafico<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>Utile e comodo strumento per marcare l\u2019accento grafico.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>Lo strumento \u00e8 di facilissimo utilizzo.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>\u00c8 sufficiente digitare oppure copiare e incollare un testo russo nella casella collocata nella parte superiore della pagina di questo sito, quindi cliccare il pulsante <em>Annotate <\/em>per visualizzare immediatamente la parola o il testo di proprio interesse con l\u2019indicazione dell\u2019accento grafico posizionato automaticamente.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab6\" class=\"uc_ac_box elementor-repeater-item-f750557 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Russian Handwriting<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>Russian Handwriting<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"https:\/\/www.youtube.com\/watch?v=XLxzTWNhMes\">https:\/\/www.youtube.com\/watch?v=XLxzTWNhMes<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>A livello iniziale di studio della lingua o, comunque, quando si vuole imparare o esercitare il corsivo manoscritto.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p>Alfabeto cirillico russo corsivo<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>Il videotutorial, disponibile gratuitamente su YouTube, mostra il modo corretto in cui scrivere i vari grafemi in corsivo, maiuscolo e minuscolo.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>La risorsa mostra non solo come scrivere correttamente ad uno ad uno i vari\u00a0 grafemi dell\u2019alfabeto cirillico, ma anche come legare tra loro le lettere quando si scrive in corsivo manoscritto.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>La risorsa \u00e8 particolarmente utile per coloro che iniziano a studiare il russo, giacch\u00e9 il corsivo manoscritto solitamente costituisce una certa difficolt\u00e0 nella fase iniziale di studio di questa lingua.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab7\" class=\"uc_ac_box elementor-repeater-item-5cb7399 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Sklonenie-slova.ru<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>Sklonenie-slova.ru<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"http:\/\/sklonenie-slova.ru\/\">http:\/\/sklonenie-slova.ru\/<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>Tutti i livelli<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p>Flessione nominale (declinazione di antroponimi, toponimi, numerali e, in generale, dei sostantivi)<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>Tabelle con la flessione di sostantivi, aggettivi, numerali, pronomi e participi nei vari casi, al singolare e al plurale.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>Grazie a questa risorsa \u00e8 sufficiente digitare la forma di proprio interesse per visualizzarne immediatamente la declinazione.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>Il database contiene oltre 83.000 parole.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab8\" class=\"uc_ac_box elementor-repeater-item-ee1cd92 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Tekstometr<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"126\"><p>Nome<\/p><\/td><td width=\"524\"><p><strong><em>Tekstometr<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"126\"><p>Indirizzo Internet<\/p><\/td><td width=\"524\"><p><a href=\"https:\/\/textometr.ru\/\">https:\/\/textometr.ru\/<\/a>, <a href=\"https:\/\/textometr.ru\/text-type\">https:\/\/textometr.ru\/text-type<\/a><\/p><\/td><\/tr><tr><td width=\"126\"><p>Livello<\/p><\/td><td width=\"524\"><p>Da A1 a C2<\/p><\/td><\/tr><tr><td width=\"126\"><p>Parole chiave<\/p><\/td><td width=\"524\"><p>Indicazione del livello di difficolt\u00e0 di un testo, conteggio di caratteri e parole, parole-chiave in un testo<\/p><\/td><\/tr><tr><td width=\"126\"><p>Contenuti<\/p><\/td><td width=\"524\"><p>La risorsa serve a stabilire il livello di difficolt\u00e0 di un testo e la sua leggibilit\u00e0, oltre a individuare le parole chiave in un testo e conteggiare il numeri di parole e caratteri.<\/p><p>\u00a0<\/p><\/td><\/tr><tr><td width=\"126\"><p>Annotazioni<\/p><\/td><td width=\"524\"><p>\u00c8 possibile ottenere un elenco completo di frequenza delle parole presenti nel testo e, in secondo luogo, statistiche sulla quota di parole dell'elenco delle 5.000 parole pi\u00f9 frequenti della lingua russa nel testo.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab9\" class=\"uc_ac_box elementor-repeater-item-5a022e5 \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">EasyPronunciation<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>EasyPronunciation<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><a href=\"https:\/\/easypronunciation.com\/it\/add-stress-marks-to-russian-text\">https:\/\/easypronunciation.com\/it\/add-stress-marks-to-russian-text<\/a><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>Tutti i livelli<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p>Accento grafico<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>Lo strumento inserisce automaticamente l\u2019accento nella parola o nel testo di proprio interesse.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>Questo strumento risulta particolarmente utile nella fase iniziale di studio del russo, giacch\u00e9 l\u2019accento, essendo libero e mobile, pu\u00f2 cadere su qualsiasi sillaba e, in genere, ci\u00f2 costituisce una notevole difficolt\u00e0 per gli apprendenti principianti (e non solo!).<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>\u00c8 sufficiente scrivere o incollare nell\u2019apposita casella di testo la parola o il testo e cliccare sul pulsante \u201cAggiungi gli accenti\u201d che si trova in basso a sinistra rispetto alla casella di testo e immediatamente viene segnalato l\u2019accento grafico. L\u2019interfaccia del sito \u00e8 disponibile in varie lingue (inglese, francese, portoghese, russo, spagnolo, tedesco, cinese e giapponese), oltre all\u2019italiano.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab10\" class=\"uc_ac_box elementor-repeater-item-0a5a7af \" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Wooclap<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><table><tbody><tr><td width=\"130\"><p>Nome<\/p><\/td><td width=\"521\"><p><strong><em>Wooclap<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"130\"><p>Indirizzo Internet<\/p><\/td><td width=\"521\"><p><u><a href=\"https:\/\/www.wooclap.com\/it\">https:\/\/www.wooclap.com\/it<\/a> <\/u><\/p><\/td><\/tr><tr><td width=\"130\"><p>Livello<\/p><\/td><td width=\"521\"><p>Tutti<\/p><\/td><\/tr><tr><td width=\"130\"><p>Parole chiave<\/p><\/td><td width=\"521\"><p>Lingue straniere, e-learning, didattica a distanza, neuroscienze, ispirazione, lezioni interattive.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Contenuti<\/p><\/td><td width=\"521\"><p>Interfaccia anche in lingua italiana, la principale funzionalit\u00e0 \u00e8 la creazione delle presentazioni interattive per le lezioni sia online che in presenza con venti diverse modalit\u00e0, ossia quiz, risposta aperta, sondaggio, Brainstorming, Domanda aperta, Trova sull\u2019immagine, Domanda a scelta multipla, Sondaggio, Abbinamento, Etichettare una figura, Diapositiva, Riempi gli spazi vuoti, Scala, Ordinamento, Trova un numero, Script Concordance test, ecc., contiene anche una guida all\u2019uso della risorsa, un blog con vari articoli utili per migliorare l\u2019apprendimento.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Punti di forza e di debolezza<\/p><\/td><td width=\"521\"><p>Interfaccia molto intuitiva e grafica attraente, integrazione facile con altri strumenti educativi come Powerpoint, Zoom e altri, possibilit\u00e0 di partecipare a tutti gli studenti contemporaneamente, possibilit\u00e0 di caricare audio, video e immagini, possibilit\u00e0 di creare una presentazione direttamente con la risorsa utilizzando modelli pre-impostati oppure importarne una gi\u00e0 pronta, accesso facile per gli studenti senza registrazione, possibilit\u00e0 di ricevere i messaggi e le reazioni istantanee dagli utenti Punti di debolezza: non rilevati.<\/p><p>Risorsa affidabile, di facile utilizzo e di elevata interattivit\u00e0, che consente di mantenere alta la motivazione degli studenti.<\/p><p>Presenza di una guida all\u2019uso con spiegazioni chiare e sintetiche.<\/p><p>Possibilit\u00e0 di realizzare quiz di revisione per monitorare e valutare i progressi degli studenti nella lingua <em>target <\/em>ad esempio mediate esercizi a scelta multipla o a risposta aperta.<\/p><p>Possibilit\u00e0 di individuare in tempo reale temi a argomenti in cui gli studenti dimostrano di avere lacune.<\/p><\/td><\/tr><tr><td width=\"130\"><p>Annotazioni<\/p><\/td><td width=\"521\"><p>L\u2019interfaccia \u00e8 disponibile anche in lingua italiana, il che garantisce un\u2019esperienza utente confortevole per gli apprendenti italofoni.<\/p><p>La risorsa, che consente la creazione di presentazioni interattive sia per lezioni in presenza che a distanza, favorisce la partecipazione attiva degli studenti e l\u2019interazione tra di loro.<\/p><p>La risorsa pu\u00f2 essere utilmente impiegata per lo sviluppo della competenza fonetica e fonologica (ad esempio, di possono realizzare file audio da proporre agli studenti che, a loro volta, possono registrare la loro pronuncia); si possono realizzare quiz e attivit\u00e0 di ascolto per sviluppare la comprensione orale. Si possono realizzare attivit\u00e0 mirate alla comprensione scritta. Per lo sviluppo della competenza lessicale si possono realizzare quiz interattivi relativi al lessico (ad esempio, mediante l\u2019abbinamento dei vocaboli ai loro traducenti e\/o alle loro definizioni). Per lo sviluppo della competenza morfosintattica si possono realizzare mirati esercizi interattivi (ad esempio, esercizi di completamento, di riempimento e di inserimento con la forma corretta richiesta).<\/p><p>La risorsa pu\u00f2 altres\u00ec essere impiegata per lavorare sulla combinabilit\u00e0 delle parole.<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n  <\/div>\n<\/div>\n\t\t\t<!-- end Content Accordion -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e318c5c elementor-widget elementor-widget-spacer\" data-id=\"e318c5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25419d3 elementor-widget elementor-widget-image\" data-id=\"25419d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian-1024x1024.png\" class=\"attachment-large size-large wp-image-65\" alt=\"\" srcset=\"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian-1024x1024.png 1024w, https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian-300x300.png 300w, https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian-150x150.png 150w, https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian-768x768.png 768w, https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian.png 1254w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n\n<\/div>\n\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Repertorio ragionato dei SITI e delle RISORSE ONLINE per l&#8217;apprendimento e l&#8217;insegnamento del russo Competenza fonetica e fonologica Tra le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-6","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home - Repertorio Siti e Risorse per il Russo - Repertorio Siti e Risorse per il Russo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Repertorio Siti e Risorse per il Russo - Repertorio Siti e Risorse per il Russo\" \/>\n<meta property=\"og:description\" content=\"Repertorio ragionato dei SITI e delle RISORSE ONLINE per l&#8217;apprendimento e l&#8217;insegnamento del russo Competenza fonetica e fonologica Tra le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/\" \/>\n<meta property=\"og:site_name\" content=\"Repertorio Siti e Risorse per il Russo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T07:09:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"38 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/\",\"name\":\"Home - Repertorio Siti e Risorse per il Russo - Repertorio Siti e Risorse per il Russo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/wp-content\\\/uploads\\\/sites\\\/108\\\/2026\\\/06\\\/russian2-1024x683.png\",\"datePublished\":\"2026-06-18T08:14:10+00:00\",\"dateModified\":\"2026-07-07T07:09:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/wp-content\\\/uploads\\\/sites\\\/108\\\/2026\\\/06\\\/russian2.png\",\"contentUrl\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/wp-content\\\/uploads\\\/sites\\\/108\\\/2026\\\/06\\\/russian2.png\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home &#8211; Repertorio Siti e Risorse per il Russo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/#website\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/\",\"name\":\"Repertorio Siti e Risorse per il Russo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/#organization\",\"name\":\"Repertorio Siti e Risorse per il Russo\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/wp-content\\\/uploads\\\/sites\\\/108\\\/2026\\\/06\\\/circle-white.png\",\"contentUrl\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/wp-content\\\/uploads\\\/sites\\\/108\\\/2026\\\/06\\\/circle-white.png\",\"width\":400,\"height\":394,\"caption\":\"Repertorio Siti e Risorse per il Russo\"},\"image\":{\"@id\":\"https:\\\/\\\/portale2.unime.it\\\/repertoriositierisorseperilrusso\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - Repertorio Siti e Risorse per il Russo - Repertorio Siti e Risorse per il Russo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/","og_locale":"it_IT","og_type":"article","og_title":"Home - Repertorio Siti e Risorse per il Russo - Repertorio Siti e Risorse per il Russo","og_description":"Repertorio ragionato dei SITI e delle RISORSE ONLINE per l&#8217;apprendimento e l&#8217;insegnamento del russo Competenza fonetica e fonologica Tra le [&hellip;]","og_url":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/","og_site_name":"Repertorio Siti e Risorse per il Russo","article_modified_time":"2026-07-07T07:09:24+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"38 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/","url":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/","name":"Home - Repertorio Siti e Risorse per il Russo - Repertorio Siti e Risorse per il Russo","isPartOf":{"@id":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/#primaryimage"},"image":{"@id":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/#primaryimage"},"thumbnailUrl":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian2-1024x683.png","datePublished":"2026-06-18T08:14:10+00:00","dateModified":"2026-07-07T07:09:24+00:00","breadcrumb":{"@id":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/#primaryimage","url":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian2.png","contentUrl":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/russian2.png","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/"},{"@type":"ListItem","position":2,"name":"Home &#8211; Repertorio Siti e Risorse per il Russo"}]},{"@type":"WebSite","@id":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/#website","url":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/","name":"Repertorio Siti e Risorse per il Russo","description":"","publisher":{"@id":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/#organization","name":"Repertorio Siti e Risorse per il Russo","url":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/#\/schema\/logo\/image\/","url":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/circle-white.png","contentUrl":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-content\/uploads\/sites\/108\/2026\/06\/circle-white.png","width":400,"height":394,"caption":"Repertorio Siti e Risorse per il Russo"},"image":{"@id":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-json\/wp\/v2\/pages\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-json\/wp\/v2\/comments?post=6"}],"version-history":[{"count":38,"href":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-json\/wp\/v2\/pages\/6\/revisions"}],"predecessor-version":[{"id":77,"href":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-json\/wp\/v2\/pages\/6\/revisions\/77"}],"wp:attachment":[{"href":"https:\/\/portale2.unime.it\/repertoriositierisorseperilrusso\/wp-json\/wp\/v2\/media?parent=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}